{"id":10760,"date":"2025-09-17T09:34:09","date_gmt":"2025-09-17T08:34:09","guid":{"rendered":"https:\/\/ksapa.org\/fr\/?p=10760"},"modified":"2025-12-03T15:42:00","modified_gmt":"2025-12-03T14:42:00","slug":"impacts-qualitatifs-sur-la-supply-chain-du-caoutchouc-naturel","status":"publish","type":"post","link":"https:\/\/ksapa.org\/fr\/impacts-qualitatifs-sur-la-supply-chain-du-caoutchouc-naturel\/","title":{"rendered":"Impacts qualitatifs sur la supply chain du caoutchouc naturel"},"content":{"rendered":"\n<p><strong>Ksapa accompagne Michelin, leader de l&rsquo;industrie automobile, et d&rsquo;autres entreprises dans leur engagement en faveur d&rsquo;une extraction durable du caoutchouc naturel. L&rsquo;engagement de ces entreprises en faveur de l&rsquo;am\u00e9lioration des revenus des producteurs de caoutchouc, de la transparence, ainsi que des conditions de travail dans l&rsquo;extraction des mati\u00e8res premi\u00e8res est illustr\u00e9 par le <a href=\"https:\/\/ksapa.org\/about-us\/our-case-studies\/providing-access-to-training-to-smallholders-ksapa-case-study\/\">projet CASCADE (Committed Actions for Smallholders Capacity Development)<\/a> mis en \u0153uvre \u00e0 Sumatra depuis 2020. Ce projet est le premier \u00e0 int\u00e9grer l&rsquo;ensemble de la cha\u00eene d&rsquo;approvisionnement : les petits exploitants agricoles et leurs partenaires, une entreprise de transformation du caoutchouc naturel, un fabricant de pneus et un constructeur automobile.<\/strong><\/p>\n\n\n\n<p>Dans le cadre de ce programme, Ksapa est responsable de la conception et du d\u00e9ploiement des efforts de renforcement des capacit\u00e9s \u00e0 l&rsquo;aide de sa solution SUTTI afin de soutenir les producteurs de caoutchouc de Sumatra. Le renforcement des capacit\u00e9s s&rsquo;articule autour de trois piliers : la productivit\u00e9 du caoutchouc, la diversification et la sensibilisation aux droits sociaux et humains. Ksapa et son partenaire local SETARA Jambi ont commenc\u00e9 \u00e0 former les agriculteurs en 2021.<\/p>\n\n\n\n<p>Dans cet article, Ksapa revient sur les r\u00e9sultats de plusieurs enqu\u00eates d&rsquo;\u00e9valuation d&rsquo;impact qualitatives men\u00e9es aupr\u00e8s des agriculteurs plusieurs mois apr\u00e8s avoir re\u00e7u une formation sur les pratiques de culture du caoutchouc.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-projet-cascade-promouvoir-l-extraction-durable-du-caoutchouc-naturel\">Projet CASCADE : Promouvoir l&rsquo;extraction durable du caoutchouc naturel<\/h2>\n\n\n\n<p>L&rsquo;Indon\u00e9sie est l&rsquo;une des plus importantes r\u00e9gions de production de caoutchouc au monde. Porsche et Michelin ont identifi\u00e9 des risques de durabilit\u00e9 dans la cha\u00eene d&rsquo;approvisionnement du caoutchouc en utilisant RubberWay, une application sp\u00e9cialement d\u00e9velopp\u00e9e \u00e0 cet effet, et en menant des discussions avec les acteurs du march\u00e9. Cette \u00e9valuation des risques a permis d&rsquo;identifier la zone prioritaire de Jambi, \u00e0 Sumatra, comme point de d\u00e9part.<\/p>\n\n\n\n<p>Pour des fabricants tel que Michelin, le caoutchouc est une mati\u00e8re premi\u00e8re essentielle, car il est utilis\u00e9 dans de nombreuses pi\u00e8ces de leurs produits. C&rsquo;est pourquoi <a href=\"https:\/\/ksapa.org\/supporting-indonesian-rubber-plantation-farmers-with-porsche-and-michelin\/\">Michelin et ses partenaires se sont engag\u00e9s \u00e0 soutenir les petits planteurs de Sumatra<\/a> dans l&rsquo;extraction du caoutchouc, en collaboration avec Ksapa. \u00c0 ce titre, le programme vise \u00e0 former 6 500 petits exploitants afin de rendre les m\u00e9thodes d&rsquo;extraction plus respectueuses de l&rsquo;environnement et plus efficaces. \u00c0 ce jour, plus de 3 000 producteurs de caoutchouc ont \u00e9t\u00e9 form\u00e9s par le programme.<\/p>\n\n\n\n<p>Comme d\u00e9crit dans un <a href=\"https:\/\/ksapa.org\/sutti-program-boosts-indonesian-rubber-smallholders-livelihood\/\">article pr\u00e9c\u00e9dent<\/a>, Ksapa utilise sa <a href=\"https:\/\/ksapa.org\/activate\/sutti-scale-up-training-traceability-impact\/\">solution SUTTI<\/a> pour calibrer et d\u00e9ployer CASCADE. SUTTI est un programme \u00e0 grande \u00e9chelle qui s&rsquo;appuie sur un mod\u00e8le hybride de renforcement des capacit\u00e9s. De plus, la suite num\u00e9rique SUTTI de Ksapa optimise l&rsquo;acc\u00e8s \u00e0 la formation via un outil d&rsquo;apprentissage en ligne et suit l&rsquo;impact du programme par rapport aux objectifs de performance sociale, environnementale et \u00e9conomique. Cela aide les groupes industriels \u00e0 mieux comprendre leur carte d&rsquo;approvisionnement et donne aux petits exploitants le contr\u00f4le de leur exploitation agricole.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-impact-de-cascade-apprentissages-centres-sur-les-besoins-de-l-agriculteur-pour-des-impacts-concrets\">Impact de CASCADE : Apprentissages centr\u00e9s sur les besoins de l\u2019agriculteur pour des impacts concrets<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-une-methodologie-centree-sur-l-agriculteur-pour-une-plus-grande-satisfaction\"><strong>UNE M\u00c9THODOLOGIE CENTR\u00c9E SUR L&rsquo;AGRICULTEUR POUR UNE PLUS GRANDE SATISFACTION<\/strong><\/h3>\n\n\n\n<p>SUTTI est premi\u00e8rement con\u00e7u pour permettre aux petits producteurs d&rsquo;atteindre une plus grande r\u00e9silience en dispensant une formation professionnelle sur des sujets prioritaires allant des comp\u00e9tences agricoles \u00e0 la sant\u00e9 et \u00e0 la s\u00e9curit\u00e9, en passant par la biodiversit\u00e9, etc. La formation dispens\u00e9e repose sur une compr\u00e9hension approfondie des besoins fondamentaux des petits exploitants. Ce diagnostic et cette analyse \u00e0 360 degr\u00e9s centr\u00e9s sur l&rsquo;agriculteur sont fondamentaux pour la bonne mise en \u0153uvre des projets SUTTI.<\/p>\n\n\n\n<p>En effet, gr\u00e2ce \u00e0 la phase de diagnostic, Ksapa identifie et classe les interventions en tant que gains rapides (\u00ab&nbsp;quick wins&nbsp;\u00bb) ou interventions \u00e0 moyen terme. Les gains rapides sont des actions dont la mise en \u0153uvre par les agriculteurs ne n\u00e9cessite pas beaucoup de temps ou d&rsquo;investissement et qui apportent des b\u00e9n\u00e9fices dans un court laps de temps. Il est essentiel de commencer le processus de renforcement des capacit\u00e9s par des actions \u00e0 effet rapide permettant d&rsquo;instaurer la confiance avec les agriculteurs, puis d&rsquo;engager des strat\u00e9gies plus complexes.<\/p>\n\n\n\n<p>La premi\u00e8re formation dispens\u00e9e par Ksapa et son partenaire local SETARA est bas\u00e9 sur les pratiques de culture de l&rsquo;h\u00e9v\u00e9a d\u00e9livrant des impacts rapides. Le r\u00e9sultat de l&rsquo;enqu\u00eate &#8211; men\u00e9e aupr\u00e8s de 50% des agriculteurs (1,500 parmi 3,000) ayant re\u00e7u une formation au moins 6 mois auparavant &#8211; est que 89% d&rsquo;entre eux sont satisfaits ou tr\u00e8s satisfaits de la formation. Ce r\u00e9sultat doit \u00e9galement \u00eatre consid\u00e9r\u00e9 en comparaison avec les programmes de formation traditionnels qui ont g\u00e9n\u00e9ralement un taux de satisfaction de 50 \u00e0 60% maximum.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"738\" height=\"300\" src=\"https:\/\/ksapa.org\/fr\/wp-content\/uploads\/sites\/1\/2025\/09\/image.png\" alt=\"\" class=\"wp-image-10761\"\/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-une-methodologie-de-formation-unique-combinant-presentiel-amp-digital\"><strong>UNE M\u00c9THODOLOGIE DE FORMATION UNIQUE COMBINANT PRESENTIEL &amp; DIGITAL<\/strong><\/h3>\n\n\n\n<p>L&rsquo;approche de la formation de Ksapa a notamment \u00e9t\u00e9 salu\u00e9e par les agriculteurs interrog\u00e9s dans le cadre de l&rsquo;enqu\u00eate. En effet, la combinaison d&rsquo;un contenu de formation adapt\u00e9 et d&rsquo;une p\u00e9dagogie ad\u00e9quate avec des capacit\u00e9s d&rsquo;apprentissage en ligne s&rsquo;est av\u00e9r\u00e9e d\u00e9cisive sur l&rsquo;adoption des pratiques par les agriculteurs. En travaillant conjointement avec les partenaires locaux et Michelin, Ksapa a \u00e9t\u00e9 en mesure d&rsquo;\u00e9laborer un contenu facile \u00e0 comprendre et pertinent pour les agriculteurs. Le fait d&rsquo;offrir des formations dans un format hybride, en utilisant des moyens pr\u00e9sentiels et num\u00e9riques, a \u00e9galement permis aux agriculteurs d&rsquo;approfondir continuellement les pratiques pour une adoption maximale.<\/p>\n\n\n\n<p>Alors que la plupart des producteurs de caoutchouc sont \u00e2g\u00e9s et qu\u2019ils ne sont pas familiaris\u00e9s avec le num\u00e9rique, le soutien continu de Ksapa et SETARA Jambi a aid\u00e9 les agriculteurs \u00e0 comprendre la valeur de l&rsquo;application SUTTI dans leur parcours de formation. S&rsquo;appuyant sur une infrastructure \u00ab&nbsp;low-tech&nbsp;\u00bb (fonctionnement hors ligne, page web au lieu d&rsquo;une application, fonctionnalit\u00e9s de synth\u00e8se vocale&#8230;), l&rsquo;application SUTTI est devenue un \u00e9l\u00e9ment central de la m\u00e9thodologie de formation CASCADE. En cons\u00e9quence, les agriculteurs passent en moyenne 1,5 heure par semaine sur l&rsquo;application pour apprendre de nouvelles pratiques, revoir le contenu et partager des donn\u00e9es.<\/p>\n\n\n\n<p>Par ailleurs, la pertinence des enseignements dispens\u00e9s a aid\u00e9 les agriculteurs \u00e0 relever des d\u00e9fis qui n&rsquo;avaient pas \u00e9t\u00e9 r\u00e9solus. Ainsi, les pratiques diffus\u00e9es ont eu un impact important sur les agriculteurs qui ont rapidement compris la valeur de ces formations. En cons\u00e9quence, la plupart des pratiques ont \u00e9t\u00e9 adopt\u00e9es par les agriculteurs.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"738\" height=\"378\" src=\"https:\/\/ksapa.org\/fr\/wp-content\/uploads\/sites\/1\/2025\/09\/image-1.png\" alt=\"\" class=\"wp-image-10762\"\/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-amelioration-du-niveau-de-vie-des-agriculteurs\"><strong>AM\u00c9LIORATION DU NIVEAU DE VIE DES AGRICULTEURS<\/strong><\/h3>\n\n\n\n<p>Les agriculteurs appliquant ces pratiques ont eu l&rsquo;opportunit\u00e9 de constater par eux-m\u00eames les impacts positifs induits apr\u00e8s quelques mois. Alors que cette formation se concentrait sur la culture du caoutchouc et la productivit\u00e9, nous avons observ\u00e9 que les agriculteurs ont fait \u00e9tat d&rsquo;impacts multiples \u00e0 travers diff\u00e9rentes dimensions : \u00e9conomique, agronomique, sant\u00e9&#8230; Ces \u00e9tudes d&rsquo;impact qualitatives prouvent donc une fois de plus l&rsquo;int\u00e9r\u00eat de ces pratiques \u00e0 impact rapide pour les agriculteurs.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"738\" height=\"336\" src=\"https:\/\/ksapa.org\/fr\/wp-content\/uploads\/sites\/1\/2025\/09\/image-2.png\" alt=\"\" class=\"wp-image-10763\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"738\" height=\"388\" src=\"https:\/\/ksapa.org\/fr\/wp-content\/uploads\/sites\/1\/2025\/09\/image-3.png\" alt=\"\" class=\"wp-image-10764\"\/><\/figure>\n\n\n\n<p>En particulier, plus de 50% des agriculteurs ont signal\u00e9 une am\u00e9lioration du rendement, de la qualit\u00e9 et de leurs revenus rapidement apr\u00e8s la formation. Dans une question sp\u00e9cifique, les agriculteurs ont d\u00e9clar\u00e9 avoir constat\u00e9 une augmentation du rendement de 20.9% en moyenne. Ces gains rapides sont essentiels car ils constituent la premi\u00e8re \u00e9tape de l&rsquo;am\u00e9lioration des revenus des producteurs de caoutchouc. Les effets combin\u00e9s, tels que l&rsquo;augmentation des rendements et la r\u00e9duction de l&rsquo;utilisation d&rsquo;intrants, am\u00e9liorent encore la rentabilit\u00e9 de leurs exploitations.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-conclusion\">Conclusion<\/h2>\n\n\n\n<p>Plusieurs leaders de l\u2019industrie automobile ont ainsi confi\u00e9 leurs efforts de d\u00e9veloppement durable \u00e0 Ksapa et \u00e0 sa solution SUTTI. En tant que mati\u00e8re premi\u00e8re cl\u00e9 dans de nombreux produits, la performance ESG des cha\u00eenes d&rsquo;approvisionnement en caoutchouc naturel doit \u00eatre am\u00e9lior\u00e9e. En particulier, dans certaines zones de culture telles que Jambi \u00e0 Sumatra, les agriculteurs sont confront\u00e9s \u00e0 de nombreux d\u00e9fis sociaux, \u00e9conomiques et agronomiques.<\/p>\n\n\n\n<p>Les r\u00e9sultats fournis jusqu&rsquo;\u00e0 pr\u00e9sent par les enqu\u00eates d&rsquo;impact qualitatives ont clairement d\u00e9montr\u00e9 l&rsquo;efficacit\u00e9 des m\u00e9thodologies de formation et de l&rsquo;approche centr\u00e9e sur les agriculteurs de Ksapa. Forts de ces r\u00e9sultats, Ksapa et ses partenaires ont \u00e9largi le programme, passant de 1 000 \u00e0 6 500 agriculteurs, afin d&rsquo;offrir une valeur ajout\u00e9e et un impact \u00e0 plus grande \u00e9chelle.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>D\u00e9couvrez l&rsquo;impact sur l&rsquo;am\u00e9lioration des revenus des producteurs de caoutchouc permise par le projet CASCADE<\/p>\n","protected":false},"author":75,"featured_media":10467,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2694,215,154,2697,131],"tags":[140,146,147,148,2815,149,150],"class_list":["post-10760","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-engagement-local","category-impact","category-inclusion","category-paysans-du-sud","category-resilience","tag-droits-de-lhomme","tag-leadership","tag-partie-prenante","tag-rse","tag-sutti","tag-technologies","tag-transparence"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Impacts qualitatifs sur la supply chain du caoutchouc naturel<\/title>\n<meta name=\"description\" content=\"D\u00e9couvrez l&#039;impact sur l&#039;am\u00e9lioration des revenus des producteurs de caoutchouc permise par le projet CASCADE\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ksapa.org\/fr\/impacts-qualitatifs-sur-la-supply-chain-du-caoutchouc-naturel\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Impacts qualitatifs sur la supply chain du caoutchouc naturel\" \/>\n<meta property=\"og:description\" content=\"D\u00e9couvrez l&#039;impact sur l&#039;am\u00e9lioration des revenus des producteurs de caoutchouc permise par le projet CASCADE\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ksapa.org\/fr\/impacts-qualitatifs-sur-la-supply-chain-du-caoutchouc-naturel\/\" \/>\n<meta property=\"og:site_name\" content=\"Ksapa - fr\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-17T08:34:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-03T14:42:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ksapa.org\/fr\/wp-content\/uploads\/sites\/1\/2025\/06\/pexels-alexeydemidov-10042307-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Adrien Covo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@KsapaOrg\" \/>\n<meta name=\"twitter:site\" content=\"@KsapaOrg\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Adrien Covo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/impacts-qualitatifs-sur-la-supply-chain-du-caoutchouc-naturel\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/impacts-qualitatifs-sur-la-supply-chain-du-caoutchouc-naturel\\\/\"},\"author\":{\"name\":\"Adrien Covo\",\"@id\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/#\\\/schema\\\/person\\\/5c5037e344a16220951fc1019696033f\"},\"headline\":\"Impacts qualitatifs sur la supply chain du caoutchouc naturel\",\"datePublished\":\"2025-09-17T08:34:09+00:00\",\"dateModified\":\"2025-12-03T14:42:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/impacts-qualitatifs-sur-la-supply-chain-du-caoutchouc-naturel\\\/\"},\"wordCount\":1440,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/impacts-qualitatifs-sur-la-supply-chain-du-caoutchouc-naturel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/1\\\/2025\\\/06\\\/pexels-alexeydemidov-10042307-scaled.jpg\",\"keywords\":[\"Droits de l\u2019Homme\",\"Leadership\",\"Partie prenante\",\"RSE\",\"SUTTI\",\"Technologies\",\"Transparence\"],\"articleSection\":[\"Engagement Local\",\"Impact\",\"Inclusion\",\"Paysans du Sud\",\"R\u00e9silience\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/ksapa.org\\\/fr\\\/impacts-qualitatifs-sur-la-supply-chain-du-caoutchouc-naturel\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/impacts-qualitatifs-sur-la-supply-chain-du-caoutchouc-naturel\\\/\",\"url\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/impacts-qualitatifs-sur-la-supply-chain-du-caoutchouc-naturel\\\/\",\"name\":\"Impacts qualitatifs sur la supply chain du caoutchouc naturel\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/impacts-qualitatifs-sur-la-supply-chain-du-caoutchouc-naturel\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/impacts-qualitatifs-sur-la-supply-chain-du-caoutchouc-naturel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/1\\\/2025\\\/06\\\/pexels-alexeydemidov-10042307-scaled.jpg\",\"datePublished\":\"2025-09-17T08:34:09+00:00\",\"dateModified\":\"2025-12-03T14:42:00+00:00\",\"description\":\"D\u00e9couvrez l'impact sur l'am\u00e9lioration des revenus des producteurs de caoutchouc permise par le projet CASCADE\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/impacts-qualitatifs-sur-la-supply-chain-du-caoutchouc-naturel\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ksapa.org\\\/fr\\\/impacts-qualitatifs-sur-la-supply-chain-du-caoutchouc-naturel\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/impacts-qualitatifs-sur-la-supply-chain-du-caoutchouc-naturel\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/1\\\/2025\\\/06\\\/pexels-alexeydemidov-10042307-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/1\\\/2025\\\/06\\\/pexels-alexeydemidov-10042307-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"D\u00e9couvrez l'impact sur l'am\u00e9lioration des revenus des producteurs de caoutchouc permise par le projet CASCADE\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/impacts-qualitatifs-sur-la-supply-chain-du-caoutchouc-naturel\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Impacts qualitatifs sur la supply chain du caoutchouc naturel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/\",\"name\":\"Ksapa - fr\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/#organization\",\"name\":\"ksapa\",\"url\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/1\\\/2019\\\/06\\\/icone-ksapa.jpg\",\"contentUrl\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/1\\\/2019\\\/06\\\/icone-ksapa.jpg\",\"width\":\"442\",\"height\":\"421\",\"caption\":\"ksapa\"},\"image\":{\"@id\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/KsapaOrg\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/#\\\/schema\\\/person\\\/5c5037e344a16220951fc1019696033f\",\"name\":\"Adrien Covo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/ksapa.org\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Adrien-Covo.jpg\",\"url\":\"https:\\\/\\\/ksapa.org\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Adrien-Covo.jpg\",\"contentUrl\":\"https:\\\/\\\/ksapa.org\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Adrien-Covo.jpg\",\"caption\":\"Adrien Covo\"},\"description\":\"Adrien is a SUTTI Program Officer. He\u2019s responsible for the development, operational implementation, and monitoring of SUTTI programs. He participates in designing financial structuring schemes leveraging SUTTI\u2019s impacts. He has previous experiences in various industries, within public, private, and non-profit organizations. Before joining, he was involved in microfinance and social entrepreneurship initiatives in Cambodia and the Philippines, after working for Danone and RATP. He holds a Master\u2019s in Finance from Paris-Dauphine University, as well as a Master in Management from ESSEC Business School. He speaks French, English, and Spanish.\",\"url\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/author\\\/acovo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Impacts qualitatifs sur la supply chain du caoutchouc naturel","description":"D\u00e9couvrez l'impact sur l'am\u00e9lioration des revenus des producteurs de caoutchouc permise par le projet CASCADE","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ksapa.org\/fr\/impacts-qualitatifs-sur-la-supply-chain-du-caoutchouc-naturel\/","og_locale":"fr_FR","og_type":"article","og_title":"Impacts qualitatifs sur la supply chain du caoutchouc naturel","og_description":"D\u00e9couvrez l'impact sur l'am\u00e9lioration des revenus des producteurs de caoutchouc permise par le projet CASCADE","og_url":"https:\/\/ksapa.org\/fr\/impacts-qualitatifs-sur-la-supply-chain-du-caoutchouc-naturel\/","og_site_name":"Ksapa - fr","article_published_time":"2025-09-17T08:34:09+00:00","article_modified_time":"2025-12-03T14:42:00+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/ksapa.org\/fr\/wp-content\/uploads\/sites\/1\/2025\/06\/pexels-alexeydemidov-10042307-scaled.jpg","type":"image\/jpeg"}],"author":"Adrien Covo","twitter_card":"summary_large_image","twitter_creator":"@KsapaOrg","twitter_site":"@KsapaOrg","twitter_misc":{"\u00c9crit par":"Adrien Covo","Dur\u00e9e de lecture estim\u00e9e":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ksapa.org\/fr\/impacts-qualitatifs-sur-la-supply-chain-du-caoutchouc-naturel\/#article","isPartOf":{"@id":"https:\/\/ksapa.org\/fr\/impacts-qualitatifs-sur-la-supply-chain-du-caoutchouc-naturel\/"},"author":{"name":"Adrien Covo","@id":"https:\/\/ksapa.org\/fr\/#\/schema\/person\/5c5037e344a16220951fc1019696033f"},"headline":"Impacts qualitatifs sur la supply chain du caoutchouc naturel","datePublished":"2025-09-17T08:34:09+00:00","dateModified":"2025-12-03T14:42:00+00:00","mainEntityOfPage":{"@id":"https:\/\/ksapa.org\/fr\/impacts-qualitatifs-sur-la-supply-chain-du-caoutchouc-naturel\/"},"wordCount":1440,"commentCount":0,"publisher":{"@id":"https:\/\/ksapa.org\/fr\/#organization"},"image":{"@id":"https:\/\/ksapa.org\/fr\/impacts-qualitatifs-sur-la-supply-chain-du-caoutchouc-naturel\/#primaryimage"},"thumbnailUrl":"https:\/\/ksapa.org\/fr\/wp-content\/uploads\/sites\/1\/2025\/06\/pexels-alexeydemidov-10042307-scaled.jpg","keywords":["Droits de l\u2019Homme","Leadership","Partie prenante","RSE","SUTTI","Technologies","Transparence"],"articleSection":["Engagement Local","Impact","Inclusion","Paysans du Sud","R\u00e9silience"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ksapa.org\/fr\/impacts-qualitatifs-sur-la-supply-chain-du-caoutchouc-naturel\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ksapa.org\/fr\/impacts-qualitatifs-sur-la-supply-chain-du-caoutchouc-naturel\/","url":"https:\/\/ksapa.org\/fr\/impacts-qualitatifs-sur-la-supply-chain-du-caoutchouc-naturel\/","name":"Impacts qualitatifs sur la supply chain du caoutchouc naturel","isPartOf":{"@id":"https:\/\/ksapa.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ksapa.org\/fr\/impacts-qualitatifs-sur-la-supply-chain-du-caoutchouc-naturel\/#primaryimage"},"image":{"@id":"https:\/\/ksapa.org\/fr\/impacts-qualitatifs-sur-la-supply-chain-du-caoutchouc-naturel\/#primaryimage"},"thumbnailUrl":"https:\/\/ksapa.org\/fr\/wp-content\/uploads\/sites\/1\/2025\/06\/pexels-alexeydemidov-10042307-scaled.jpg","datePublished":"2025-09-17T08:34:09+00:00","dateModified":"2025-12-03T14:42:00+00:00","description":"D\u00e9couvrez l'impact sur l'am\u00e9lioration des revenus des producteurs de caoutchouc permise par le projet CASCADE","breadcrumb":{"@id":"https:\/\/ksapa.org\/fr\/impacts-qualitatifs-sur-la-supply-chain-du-caoutchouc-naturel\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ksapa.org\/fr\/impacts-qualitatifs-sur-la-supply-chain-du-caoutchouc-naturel\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/ksapa.org\/fr\/impacts-qualitatifs-sur-la-supply-chain-du-caoutchouc-naturel\/#primaryimage","url":"https:\/\/ksapa.org\/fr\/wp-content\/uploads\/sites\/1\/2025\/06\/pexels-alexeydemidov-10042307-scaled.jpg","contentUrl":"https:\/\/ksapa.org\/fr\/wp-content\/uploads\/sites\/1\/2025\/06\/pexels-alexeydemidov-10042307-scaled.jpg","width":2560,"height":1707,"caption":"D\u00e9couvrez l'impact sur l'am\u00e9lioration des revenus des producteurs de caoutchouc permise par le projet CASCADE"},{"@type":"BreadcrumbList","@id":"https:\/\/ksapa.org\/fr\/impacts-qualitatifs-sur-la-supply-chain-du-caoutchouc-naturel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ksapa.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Impacts qualitatifs sur la supply chain du caoutchouc naturel"}]},{"@type":"WebSite","@id":"https:\/\/ksapa.org\/fr\/#website","url":"https:\/\/ksapa.org\/fr\/","name":"Ksapa - fr","description":"","publisher":{"@id":"https:\/\/ksapa.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ksapa.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/ksapa.org\/fr\/#organization","name":"ksapa","url":"https:\/\/ksapa.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/ksapa.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/ksapa.org\/fr\/wp-content\/uploads\/sites\/1\/2019\/06\/icone-ksapa.jpg","contentUrl":"https:\/\/ksapa.org\/fr\/wp-content\/uploads\/sites\/1\/2019\/06\/icone-ksapa.jpg","width":"442","height":"421","caption":"ksapa"},"image":{"@id":"https:\/\/ksapa.org\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/KsapaOrg"]},{"@type":"Person","@id":"https:\/\/ksapa.org\/fr\/#\/schema\/person\/5c5037e344a16220951fc1019696033f","name":"Adrien Covo","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/ksapa.org\/wp-content\/uploads\/2023\/07\/Adrien-Covo.jpg","url":"https:\/\/ksapa.org\/wp-content\/uploads\/2023\/07\/Adrien-Covo.jpg","contentUrl":"https:\/\/ksapa.org\/wp-content\/uploads\/2023\/07\/Adrien-Covo.jpg","caption":"Adrien Covo"},"description":"Adrien is a SUTTI Program Officer. He\u2019s responsible for the development, operational implementation, and monitoring of SUTTI programs. He participates in designing financial structuring schemes leveraging SUTTI\u2019s impacts. He has previous experiences in various industries, within public, private, and non-profit organizations. Before joining, he was involved in microfinance and social entrepreneurship initiatives in Cambodia and the Philippines, after working for Danone and RATP. He holds a Master\u2019s in Finance from Paris-Dauphine University, as well as a Master in Management from ESSEC Business School. He speaks French, English, and Spanish.","url":"https:\/\/ksapa.org\/fr\/author\/acovo\/"}]}},"_links":{"self":[{"href":"https:\/\/ksapa.org\/fr\/wp-json\/wp\/v2\/posts\/10760","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ksapa.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ksapa.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ksapa.org\/fr\/wp-json\/wp\/v2\/users\/75"}],"replies":[{"embeddable":true,"href":"https:\/\/ksapa.org\/fr\/wp-json\/wp\/v2\/comments?post=10760"}],"version-history":[{"count":4,"href":"https:\/\/ksapa.org\/fr\/wp-json\/wp\/v2\/posts\/10760\/revisions"}],"predecessor-version":[{"id":10778,"href":"https:\/\/ksapa.org\/fr\/wp-json\/wp\/v2\/posts\/10760\/revisions\/10778"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ksapa.org\/fr\/wp-json\/wp\/v2\/media\/10467"}],"wp:attachment":[{"href":"https:\/\/ksapa.org\/fr\/wp-json\/wp\/v2\/media?parent=10760"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ksapa.org\/fr\/wp-json\/wp\/v2\/categories?post=10760"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ksapa.org\/fr\/wp-json\/wp\/v2\/tags?post=10760"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}