{"id":320,"date":"2018-10-08T21:22:05","date_gmt":"2018-10-08T20:22:05","guid":{"rendered":"https:\/\/inclusive-resilient.org\/?p=320"},"modified":"2021-06-09T08:39:54","modified_gmt":"2021-06-09T07:39:54","slug":"les-medias-sociaux-ont-tue-les-rapports-rse-vive-les-medias-sociaux","status":"publish","type":"post","link":"https:\/\/ksapa.org\/fr\/les-medias-sociaux-ont-tue-les-rapports-rse-vive-les-medias-sociaux\/","title":{"rendered":"Les m\u00e9dias sociaux ont tu\u00e9 les rapports RSE. Vive les m\u00e9dias sociaux!"},"content":{"rendered":"\n<p>Cet article mis \u00e0 jour a \u00e9t\u00e9 initialement publi\u00e9 sur Le Cercle Les Echos <a rel=\"noreferrer noopener\" aria-label=\" (s\u2019ouvre dans un nouvel onglet)\" href=\"http:\/\/archives.lesechos.fr\/archives\/cercle\/2013\/09\/16\/cercle_79864.htm\" target=\"_blank\">ici<\/a><\/p>\n\n\n\n<p><strong>Quand avez-vous consult\u00e9 votre annuaire t\u00e9l\u00e9phonique pour la derni\u00e8re fois pour y chercher un num\u00e9ro de t\u00e9l\u00e9phone ? Non seulement la recherche d\u2019informations s\u2019effectue d\u00e9sormais avant tout en ligne et de mani\u00e8re cibl\u00e9e. Mais les m\u00e9dias sociaux changent aussi la perception et la consommation de cette information extra financi\u00e8re. Avec quelles implications ?<\/strong><\/p>\n\n\n\n<p>Pour les entreprises visant \u00e0 am\u00e9liorer leur contribution en faveur du d\u00e9veloppement durable, la question du reporting a \u00e9t\u00e9 importante et s&rsquo;est structur\u00e9e sur les 20 derni\u00e8res ann\u00e9es. Outil de diffusion de l\u2019information et de dialogue avec les parties prenantes, le reporting extra financier a \u00e9t\u00e9 une activit\u00e9-cl\u00e9 permettant de soutenir la cr\u00e9dibilit\u00e9 (ou non) de la d\u00e9marche d\u00e9veloppement durable d\u2019une entreprise. De plus en plus r\u00e9glement\u00e9e, par exemple en France via les exigences issues de l\u2019<a rel=\"noreferrer noopener\" href=\"http:\/\/www.medef.com\/fileadmin\/user_upload\/www.medef-corporate.fr\/document\/RSE\/MEDEF_-_Guide_Reporting_RSE_-_Mai_2012.pdf\" target=\"_blank\">article 225<\/a> de la loi Grenelle 2, l&rsquo;int\u00e9gration de consid\u00e9rations extra financi\u00e8re dans les documents de r\u00e9f\u00e9rence, et bient\u00f4t via la d\u00e9claration extra financi\u00e8re de performance (DPEF), la d\u00e9marche de reporting extra financi\u00e8re se structure majoritairement autour de la pr\u00e9paration et de la publication de rapports d\u00e9di\u00e9s, faisant \u00e9tat par exemple de la Responsabilit\u00e9 Sociale de l\u2019Entreprise (RSE).<\/p>\n\n\n\n<p>Rapports RSE, documents de r\u00e9f\u00e9rence, DPEF&#8230; ces documents sous format RSE n&rsquo;int\u00e9ressent qu&rsquo;une petite fraction d&#8217;employ\u00e9s, de consultants et concurrents et d&rsquo;\u00e9tudiants. Ils sont de plus en plus marginalis\u00e9e dans la mani\u00e8re dont les parties prenantes essentielles &#8211; clients, investisseurs, prescripteurs et influenceurs se forgent leur opinion et font leur propre \u00e9valuation. Plus personne ne se concentre sur un PDF sans approfondir en naviguant parmi des liens hypertextes et en croisant l&rsquo;information avec d&rsquo;autres sources officielles et les contenus charri\u00e9s par les m\u00e9dias sociaux (\u00e9volutions sectorielles, controverses, campagnes th\u00e9matiques, points de vue d&rsquo;experts, \u00e9volution r\u00e9glementaire&#8230;). <\/p>\n\n\n\n<h2 class=\"wp-block-heading\">D\u00e9marche RSE: d\u00e9marche de dialogue<\/h2>\n\n\n\n<p>Le principe m\u00eame d&rsquo;une d\u00e9marche RSE, c&rsquo;est d&rsquo;offrir un espace de dialogue. En r\u00e9ponse aux sceptiques y voyant un simple outil de communication et de Greenwashing, j&rsquo;ai toujours expliqu\u00e9 \u00e0 mes coll\u00e8gues, partenaires, clients, d\u00e9cideurs et \u00e9tudiants que j&rsquo;avais pu rencontrer ce qui a fait longtemps fondamentalement la diff\u00e9rence:<br><br>&#8211; Une d\u00e9marche de communication reste avant tout \u00ab\u00a0top down\u00a0\u00bb. Elle vise \u00e0 faire passer un message aupr\u00e8s d&rsquo;une audience cible pour en obtenir l&rsquo;adh\u00e9sion. Voil\u00e0 ce que je fais et comment je veux vous convaincre que c&rsquo;est la bonne mani\u00e8re de le faire.<br><br>&#8211; Une d\u00e9marche RSE reste avant tout une d\u00e9marche \u00ab\u00a0feed back\u00a0\u00bb. Elle vise \u00e0 partager une perspective et collecter du feedback pour enrichir et am\u00e9liorer cette perspective. Voil\u00e0 ce que je comprends du sujet et ce que je fais pour y travailler. Qu&rsquo;est-ce que je n&rsquo;ai pas compris et comment je peux faire mieux?<\/p>\n\n\n\n<p>D\u00e8s lors, pour que l\u2019ensemble de la d\u00e9marche extra financi\u00e8re de reporting puisse continuer \u00e0 fonctionner et rester cr\u00e9dible dans un espace o\u00f9 l&rsquo;acc\u00e8s \u00e0 l&rsquo;information s&rsquo;est non seulement compl\u00e8tement digitalis\u00e9, mais aussi renforc\u00e9 autour des m\u00e9dias sociaux, il faut revoir compl\u00e8tement l&rsquo;approche, pour conserver et adapter les moyens \u00e0 d\u00e9ployer pour cr\u00e9er les conditions d&rsquo;un dialogue cr\u00e9dible.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Pour faire du dialogue, les m\u00e9dias sociaux ont un r\u00f4le \u00e9vident!<\/strong><\/h2>\n\n\n\n<p>Si la RSE est une d\u00e9marche de dialogue, quel r\u00f4le donner aux m\u00e9dias sociaux ? Apr\u00e8s tout, les m\u00e9dias sociaux sont\u2026 sociaux, donc humains. Ils sont le catalyseur de nombreux d\u00e9bats, rumeurs, connexions permettant de lier des informations et de renforcer son regard critique sur des sujets complexes.<\/p>\n\n\n\n<p>Les r\u00e9seaux sociaux ont donn\u00e9 un sacr\u00e9 coup de vieux aux approches convenues des rapports annuels des entreprises (financiers, d\u00e9veloppement durable), avec leur lot de \u00ab Message du Directeur G\u00e9n\u00e9ral \u00bb et autres \u00ab Rapports d\u2019Examen des Commissaires aux Comptes \u00bb. D\u00e9sormais, des outils suivent le buzz des m\u00e9dias sociaux pour prendre le pouls et identifier les trajectoires structurelles et priorit\u00e9s du moment. Il n&rsquo;y a plus de distance entre le \u00ab\u00a0Directeur G\u00e9n\u00e9ral\u00a0\u00bb et les parties prenantes qui peuvent l&rsquo;interpeller directement sur Tweeter. Outre les comptes officiels, suivre certains salari\u00e9s d&rsquo;organisations permet l\u00e0 aussi de mieux comprendre ce qu&rsquo;il s&rsquo;y passe au-del\u00e0 des canaux officiels. Bref, les m\u00e9dias sociaux rendent le formalisme des rapports PDF caduque autant qu&rsquo;ils apportent de l&rsquo;information d&rsquo;une plus grande richesse et diversit\u00e9 dans de nombreux cas. <\/p>\n\n\n\n<p>D\u00e8s lors, autant s&rsquo;adapter \u00e0 cette nouvelle r\u00e9alit\u00e9? Quelques exemples:<br>&#8211; Activement impliquer les utilisateurs des donn\u00e9es (via les m\u00e9dias sociaux) via des espaces offerts sur Twitter, Instagram, Facebook ou Linkedin par exemple<br>&#8211; Utiliser les m\u00eames outils pour constamment suivre et mettre \u00e0 jour une cartographie de parties prenantes. Au-del\u00e0 des institutionnels et des acteurs convenus, les m\u00e9dias sociaux offrent aussi une fen\u00eatre sur une richesse d&rsquo;initiatives, d&rsquo;acteurs, de programmes qu&rsquo;il convient de suivre constamment afin de se connecter et entrer en dialogue avec les plus pertinentes<br>&#8211; Faire des passerelles entre les donn\u00e9es fournies par l\u2019entreprise et ce qui se  trouve ailleurs sur Internet pour cr\u00e9dibiliser et contextualiser  l\u2019information et alimenter le regard critique de l\u2019utilisateur<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Accepter de perdre la main sur les \u00e9changes?<\/strong><\/h2>\n\n\n\n<p>Il y a vraiment un risque pour des profils communicants \u00e0 accepter de perdre la main sur les contenus fournis : un bon vieux rapport PDF permettait d\u2019assurer la v\u00e9racit\u00e9 des informations fournies aux parties prenantes, ou tout du moins d\u2019en contr\u00f4ler la communication. De leur c\u00f4t\u00e9, si l\u2019utilisation des m\u00e9dias sociaux n\u2019est pas guid\u00e9e, elle peut tout simplement repr\u00e9senter une perte de temps abyssale, connecter de l\u2019information pertinente avec de grossi\u00e8res impr\u00e9cisions. Des Trolls ont une capacit\u00e9 \u00e0 faire gonfler des fausses informations rapidement&#8230; <\/p>\n\n\n\n<p>Pourtant la bataille de la communication totalement verrouill\u00e9e est d\u00e9j\u00e0 perdue depuis longtemps : n\u2019importe quelle partie prenante d\u00e9sireuse de porter un regard critique sur la performance RSE d\u2019une entreprise ne se contentera pas des informations que l\u2019entreprise voudra bien lui fournir directement. En quelques clics, il fera l\u2019effort de croiser les donn\u00e9es. N\u2019importe quel salari\u00e9 dispose d\u2019un t\u00e9l\u00e9phone et peut prendre une photo ou enregistrer ce qu\u2019il veut et le diffuser sur Facebook en quelques secondes et tweeter pour relayer l\u2019information. Ce d\u00e9bat n&rsquo;a plus lieu d&rsquo;\u00eatre, mais rappelle qu&rsquo;on n&rsquo;est bien arm\u00e9 pour faire du reporting extra financier \u00e0 l&rsquo;\u00e8re des m\u00e9dias sociaux qu&rsquo;en s&rsquo;assurant d&rsquo;avoir quelques bases en place:<br><br>&#8211; Bien conna\u00eetre ses enjeux sectoriels prioritaires pour ne pas se perdre dans le superflu. Cela n&#8217;emp\u00eache pas d&rsquo;avoir \u00e9galement une vision prospective et garder un oeil sur des signaux faibles<\/p>\n\n\n\n<p>-Bien conna\u00eetre les dynamiques sectoriels et jeux d&rsquo;acteurs pour identifier la v\u00e9racit\u00e9 des informations et rapidement balayer l&rsquo;incoh\u00e9rence et les fake news<br><br>&#8211; Conserver des espaces de r\u00e9flexion et d&rsquo;actions hors des m\u00e9dias sociaux. Non seulement certaines r\u00e9flexions demandent un temps long. Mais un livre, une \u00e9tude, le suivi d&rsquo;un travail de recherche sont autant d&rsquo;espaces indispensables sur les questions complexes qui sous-tendent aux enjeux extra financiers des entreprises<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Comment faire du reporting \u00e0 l\u2019\u00e8re des m\u00e9dias sociaux ?<\/strong><\/h2>\n\n\n\n<p>Voici ainsi quelques principes \u00e0 m\u00e9diter pour les personnes en charge de d\u00e9marche de reporting dans les entreprises, pour s\u2019adapter \u00e0 un univers de diffusion et d\u2019acc\u00e8s \u00e0 l\u2019information en pleine mutation :<\/p>\n\n\n\n<p><em><strong>\u2013 Humaniser la d\u00e9marche<\/strong><\/em>. Au lieu de d\u00e9marches d\u00e9shumanis\u00e9es derri\u00e8re des emails sans saveur de type contact@monorganisation.com, il faut sortir du bois, laisser les coll\u00e8gues porter individuellement la d\u00e9marche avec leur nom, pr\u00e9nom et email pour \u00e9crire des blogs, tweeter, repr\u00e9senter l\u2019approche de l\u2019entreprise dans son reporting.<\/p>\n\n\n\n<p><em><strong>\u2013 \u00c9couter.<\/strong><\/em>&nbsp;La participation aux m\u00e9dias sociaux, c\u2019est 99 % d\u2019\u00e9coute et 1 % de prise de parole. Identifier les bons canaux, comprendre l\u2019orientation des conversations, argumenter pour donner du relief aux donn\u00e9es disponibles dans la d\u00e9marche de reporting permettent \u00e0 la fois d\u2019expliquer et d\u2019am\u00e9liorer la d\u00e9marche de l\u2019entreprise.<\/p>\n\n\n\n<p><em><strong>\u2013 Int\u00e9grer.<\/strong><\/em> Il existe d\u00e9j\u00e0 des communaut\u00e9s, des sites et plateformes s\u00e9rieux partageant de l\u2019information pertinente. Il faut s\u2019y associer, faire des passerelles entre ces informations et ces communaut\u00e9s et les dossiers pertinents port\u00e9s par la d\u00e9marche de reporting. C\u2019est une mani\u00e8re dynamique de faire vivre les donn\u00e9es de reporting et de leur donner de la profondeur.<\/p>\n\n\n\n<p><em><strong>\u2013 Recruter.<\/strong><\/em> J\u2019observe au quotidien dans mon travail combien une fracture reste r\u00e9elle entre disons les trentenaires et les cinquantenaires. Les jeunes g\u00e9n\u00e9rations op\u00e8rent une lente, mais ind\u00e9niable mutation dans l\u2019organisation du travail individuel et collaboratif, mais surtout dans l\u2019acc\u00e8s \u00e0 l\u2019information et la ma\u00eetrise des r\u00e9seaux sociaux. Mais les cinquantenaires restent souvent les principaux d\u00e9cideurs&#8230; <\/p>\n\n\n\n<p>Dans les entreprises, il faut donc simplement accepter de recruter ces jeunes, renforcer les \u00e9quipes en place pour b\u00e9n\u00e9ficier de tout ce qui est \u00e9vident et d\u00e9j\u00e0 int\u00e9gr\u00e9 pour la g\u00e9n\u00e9ration Y, les mixer dans des \u00e9quipes d\u2019encadrement plus senior. <\/p>\n\n\n\n<p>Pour rester cr\u00e9dibles, les d\u00e9marches doivent trouver de nouveaux \u00e9quilibres permettant d\u2019entrer de plain-pied dans l\u2019\u00e8re des m\u00e9dias sociaux. Et je vous laisse avec la question suivante, comment transformer un rapport d\u00e9veloppement durable de 140 pages en un tweet de 140 caract\u00e8res? Probablement une question d&rsquo;avenir qui pourra se r\u00e9sumer \u00e0 l&rsquo;exp\u00e9rience en r\u00e9alit\u00e9 virtuelle de la mani\u00e8re dont un programme ou un produit am\u00e9liore sa performance environnementale et sociale&#8230; <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les m\u00e9dias sociaux changent totalement la production et l&rsquo;utilisation de l&rsquo;information ESG extra financi\u00e8re. Avec quelles implications ?<\/p>\n","protected":false},"author":2,"featured_media":213,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[215,2692],"tags":[139,2897,2898,143,146,2899,147,148,149,150],"class_list":["post-320","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-impact","category-reporting-extra-financier","tag-developpement-durable","tag-directive-reporting-extra-financier","tag-dpef-2020","tag-france","tag-leadership","tag-non-financial-reporting-directive-nfrd","tag-partie-prenante","tag-rse","tag-technologies","tag-transparence"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Les m\u00e9dias sociaux ont tu\u00e9 les rapports RSE. Vive les m\u00e9dias sociaux!<\/title>\n<meta name=\"description\" content=\"Les m\u00e9dias sociaux changent totalement la production et l&#039;utilisation de l&#039;information ESG extra financi\u00e8re. Avec quelles implications ?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ksapa.org\/fr\/les-medias-sociaux-ont-tue-les-rapports-rse-vive-les-medias-sociaux\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les m\u00e9dias sociaux ont tu\u00e9 les rapports RSE. Vive les m\u00e9dias sociaux!\" \/>\n<meta property=\"og:description\" content=\"Les m\u00e9dias sociaux changent totalement la production et l&#039;utilisation de l&#039;information ESG extra financi\u00e8re. Avec quelles implications ?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ksapa.org\/fr\/les-medias-sociaux-ont-tue-les-rapports-rse-vive-les-medias-sociaux\/\" \/>\n<meta property=\"og:site_name\" content=\"Ksapa - fr\" \/>\n<meta property=\"article:published_time\" content=\"2018-10-08T20:22:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-09T07:39:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ksapa.org\/fr\/wp-content\/uploads\/sites\/1\/2019\/02\/medias-sociaux-vont-ils-tuer-rapports-developpement-durable.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1088\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Farid Baddache\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Fbaddache\" \/>\n<meta name=\"twitter:site\" content=\"@KsapaOrg\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Farid Baddache\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/les-medias-sociaux-ont-tue-les-rapports-rse-vive-les-medias-sociaux\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/les-medias-sociaux-ont-tue-les-rapports-rse-vive-les-medias-sociaux\\\/\"},\"author\":{\"name\":\"Farid Baddache\",\"@id\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/#\\\/schema\\\/person\\\/04c46158d370e75b9ece9fe70d969403\"},\"headline\":\"Les m\u00e9dias sociaux ont tu\u00e9 les rapports RSE. Vive les m\u00e9dias sociaux!\",\"datePublished\":\"2018-10-08T20:22:05+00:00\",\"dateModified\":\"2021-06-09T07:39:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/les-medias-sociaux-ont-tue-les-rapports-rse-vive-les-medias-sociaux\\\/\"},\"wordCount\":1728,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/les-medias-sociaux-ont-tue-les-rapports-rse-vive-les-medias-sociaux\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/1\\\/2019\\\/02\\\/medias-sociaux-vont-ils-tuer-rapports-developpement-durable.jpg\",\"keywords\":[\"D\u00e9veloppement Durable\",\"directive reporting extra financier\",\"dpef 2020\",\"France\",\"Leadership\",\"non-financial reporting directive (nfrd)\",\"Partie prenante\",\"RSE\",\"Technologies\",\"Transparence\"],\"articleSection\":[\"Impact\",\"Reporting Extra-Financier\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/ksapa.org\\\/fr\\\/les-medias-sociaux-ont-tue-les-rapports-rse-vive-les-medias-sociaux\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/les-medias-sociaux-ont-tue-les-rapports-rse-vive-les-medias-sociaux\\\/\",\"url\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/les-medias-sociaux-ont-tue-les-rapports-rse-vive-les-medias-sociaux\\\/\",\"name\":\"Les m\u00e9dias sociaux ont tu\u00e9 les rapports RSE. Vive les m\u00e9dias sociaux!\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/les-medias-sociaux-ont-tue-les-rapports-rse-vive-les-medias-sociaux\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/les-medias-sociaux-ont-tue-les-rapports-rse-vive-les-medias-sociaux\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/1\\\/2019\\\/02\\\/medias-sociaux-vont-ils-tuer-rapports-developpement-durable.jpg\",\"datePublished\":\"2018-10-08T20:22:05+00:00\",\"dateModified\":\"2021-06-09T07:39:54+00:00\",\"description\":\"Les m\u00e9dias sociaux changent totalement la production et l'utilisation de l'information ESG extra financi\u00e8re. Avec quelles implications ?\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/les-medias-sociaux-ont-tue-les-rapports-rse-vive-les-medias-sociaux\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ksapa.org\\\/fr\\\/les-medias-sociaux-ont-tue-les-rapports-rse-vive-les-medias-sociaux\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/les-medias-sociaux-ont-tue-les-rapports-rse-vive-les-medias-sociaux\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/1\\\/2019\\\/02\\\/medias-sociaux-vont-ils-tuer-rapports-developpement-durable.jpg\",\"contentUrl\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/1\\\/2019\\\/02\\\/medias-sociaux-vont-ils-tuer-rapports-developpement-durable.jpg\",\"width\":1600,\"height\":1088,\"caption\":\"Les m\u00e9dias sociaux vont-ils tuer les rapports d\u00e9veloppement durable ?\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/les-medias-sociaux-ont-tue-les-rapports-rse-vive-les-medias-sociaux\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les m\u00e9dias sociaux ont tu\u00e9 les rapports RSE. Vive les m\u00e9dias sociaux!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/\",\"name\":\"Ksapa - fr\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/#organization\",\"name\":\"ksapa\",\"url\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/1\\\/2019\\\/06\\\/icone-ksapa.jpg\",\"contentUrl\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/1\\\/2019\\\/06\\\/icone-ksapa.jpg\",\"width\":\"442\",\"height\":\"421\",\"caption\":\"ksapa\"},\"image\":{\"@id\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/KsapaOrg\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/#\\\/schema\\\/person\\\/04c46158d370e75b9ece9fe70d969403\",\"name\":\"Farid Baddache\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/1\\\/2019\\\/02\\\/farid-baddache-blog-auteur-resilience-impact-inclusion.jpg\",\"url\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/1\\\/2019\\\/02\\\/farid-baddache-blog-auteur-resilience-impact-inclusion.jpg\",\"contentUrl\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/1\\\/2019\\\/02\\\/farid-baddache-blog-auteur-resilience-impact-inclusion.jpg\",\"caption\":\"Farid Baddache\"},\"description\":\"CEO and Co-Founder of Ksapa. Member of sustainability boards at major industrial groups and impact investment committees. Drawing on 25 years of experience working with multinationals, mid-size and small businesses across value chains, governments, and international organizations, Farid Baddache focuses on integrating human rights, climate, and ESG governance as drivers of business resilience and competitiveness. Author of several books on sustainability and responsible business. Connect on Bluesky @faridbaddache.bsky.social\",\"sameAs\":[\"http:\\\/\\\/www.ksapa.org\",\"https:\\\/\\\/x.com\\\/Fbaddache\"],\"url\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/author\\\/faridb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les m\u00e9dias sociaux ont tu\u00e9 les rapports RSE. Vive les m\u00e9dias sociaux!","description":"Les m\u00e9dias sociaux changent totalement la production et l'utilisation de l'information ESG extra financi\u00e8re. Avec quelles implications ?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ksapa.org\/fr\/les-medias-sociaux-ont-tue-les-rapports-rse-vive-les-medias-sociaux\/","og_locale":"fr_FR","og_type":"article","og_title":"Les m\u00e9dias sociaux ont tu\u00e9 les rapports RSE. Vive les m\u00e9dias sociaux!","og_description":"Les m\u00e9dias sociaux changent totalement la production et l'utilisation de l'information ESG extra financi\u00e8re. Avec quelles implications ?","og_url":"https:\/\/ksapa.org\/fr\/les-medias-sociaux-ont-tue-les-rapports-rse-vive-les-medias-sociaux\/","og_site_name":"Ksapa - fr","article_published_time":"2018-10-08T20:22:05+00:00","article_modified_time":"2021-06-09T07:39:54+00:00","og_image":[{"width":1600,"height":1088,"url":"https:\/\/ksapa.org\/fr\/wp-content\/uploads\/sites\/1\/2019\/02\/medias-sociaux-vont-ils-tuer-rapports-developpement-durable.jpg","type":"image\/jpeg"}],"author":"Farid Baddache","twitter_card":"summary_large_image","twitter_creator":"@Fbaddache","twitter_site":"@KsapaOrg","twitter_misc":{"\u00c9crit par":"Farid Baddache","Dur\u00e9e de lecture estim\u00e9e":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ksapa.org\/fr\/les-medias-sociaux-ont-tue-les-rapports-rse-vive-les-medias-sociaux\/#article","isPartOf":{"@id":"https:\/\/ksapa.org\/fr\/les-medias-sociaux-ont-tue-les-rapports-rse-vive-les-medias-sociaux\/"},"author":{"name":"Farid Baddache","@id":"https:\/\/ksapa.org\/fr\/#\/schema\/person\/04c46158d370e75b9ece9fe70d969403"},"headline":"Les m\u00e9dias sociaux ont tu\u00e9 les rapports RSE. Vive les m\u00e9dias sociaux!","datePublished":"2018-10-08T20:22:05+00:00","dateModified":"2021-06-09T07:39:54+00:00","mainEntityOfPage":{"@id":"https:\/\/ksapa.org\/fr\/les-medias-sociaux-ont-tue-les-rapports-rse-vive-les-medias-sociaux\/"},"wordCount":1728,"commentCount":0,"publisher":{"@id":"https:\/\/ksapa.org\/fr\/#organization"},"image":{"@id":"https:\/\/ksapa.org\/fr\/les-medias-sociaux-ont-tue-les-rapports-rse-vive-les-medias-sociaux\/#primaryimage"},"thumbnailUrl":"https:\/\/ksapa.org\/fr\/wp-content\/uploads\/sites\/1\/2019\/02\/medias-sociaux-vont-ils-tuer-rapports-developpement-durable.jpg","keywords":["D\u00e9veloppement Durable","directive reporting extra financier","dpef 2020","France","Leadership","non-financial reporting directive (nfrd)","Partie prenante","RSE","Technologies","Transparence"],"articleSection":["Impact","Reporting Extra-Financier"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ksapa.org\/fr\/les-medias-sociaux-ont-tue-les-rapports-rse-vive-les-medias-sociaux\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ksapa.org\/fr\/les-medias-sociaux-ont-tue-les-rapports-rse-vive-les-medias-sociaux\/","url":"https:\/\/ksapa.org\/fr\/les-medias-sociaux-ont-tue-les-rapports-rse-vive-les-medias-sociaux\/","name":"Les m\u00e9dias sociaux ont tu\u00e9 les rapports RSE. Vive les m\u00e9dias sociaux!","isPartOf":{"@id":"https:\/\/ksapa.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ksapa.org\/fr\/les-medias-sociaux-ont-tue-les-rapports-rse-vive-les-medias-sociaux\/#primaryimage"},"image":{"@id":"https:\/\/ksapa.org\/fr\/les-medias-sociaux-ont-tue-les-rapports-rse-vive-les-medias-sociaux\/#primaryimage"},"thumbnailUrl":"https:\/\/ksapa.org\/fr\/wp-content\/uploads\/sites\/1\/2019\/02\/medias-sociaux-vont-ils-tuer-rapports-developpement-durable.jpg","datePublished":"2018-10-08T20:22:05+00:00","dateModified":"2021-06-09T07:39:54+00:00","description":"Les m\u00e9dias sociaux changent totalement la production et l'utilisation de l'information ESG extra financi\u00e8re. Avec quelles implications ?","breadcrumb":{"@id":"https:\/\/ksapa.org\/fr\/les-medias-sociaux-ont-tue-les-rapports-rse-vive-les-medias-sociaux\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ksapa.org\/fr\/les-medias-sociaux-ont-tue-les-rapports-rse-vive-les-medias-sociaux\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/ksapa.org\/fr\/les-medias-sociaux-ont-tue-les-rapports-rse-vive-les-medias-sociaux\/#primaryimage","url":"https:\/\/ksapa.org\/fr\/wp-content\/uploads\/sites\/1\/2019\/02\/medias-sociaux-vont-ils-tuer-rapports-developpement-durable.jpg","contentUrl":"https:\/\/ksapa.org\/fr\/wp-content\/uploads\/sites\/1\/2019\/02\/medias-sociaux-vont-ils-tuer-rapports-developpement-durable.jpg","width":1600,"height":1088,"caption":"Les m\u00e9dias sociaux vont-ils tuer les rapports d\u00e9veloppement durable ?"},{"@type":"BreadcrumbList","@id":"https:\/\/ksapa.org\/fr\/les-medias-sociaux-ont-tue-les-rapports-rse-vive-les-medias-sociaux\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ksapa.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Les m\u00e9dias sociaux ont tu\u00e9 les rapports RSE. Vive les m\u00e9dias sociaux!"}]},{"@type":"WebSite","@id":"https:\/\/ksapa.org\/fr\/#website","url":"https:\/\/ksapa.org\/fr\/","name":"Ksapa - fr","description":"","publisher":{"@id":"https:\/\/ksapa.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ksapa.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/ksapa.org\/fr\/#organization","name":"ksapa","url":"https:\/\/ksapa.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/ksapa.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/ksapa.org\/fr\/wp-content\/uploads\/sites\/1\/2019\/06\/icone-ksapa.jpg","contentUrl":"https:\/\/ksapa.org\/fr\/wp-content\/uploads\/sites\/1\/2019\/06\/icone-ksapa.jpg","width":"442","height":"421","caption":"ksapa"},"image":{"@id":"https:\/\/ksapa.org\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/KsapaOrg"]},{"@type":"Person","@id":"https:\/\/ksapa.org\/fr\/#\/schema\/person\/04c46158d370e75b9ece9fe70d969403","name":"Farid Baddache","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/ksapa.org\/fr\/wp-content\/uploads\/sites\/1\/2019\/02\/farid-baddache-blog-auteur-resilience-impact-inclusion.jpg","url":"https:\/\/ksapa.org\/fr\/wp-content\/uploads\/sites\/1\/2019\/02\/farid-baddache-blog-auteur-resilience-impact-inclusion.jpg","contentUrl":"https:\/\/ksapa.org\/fr\/wp-content\/uploads\/sites\/1\/2019\/02\/farid-baddache-blog-auteur-resilience-impact-inclusion.jpg","caption":"Farid Baddache"},"description":"CEO and Co-Founder of Ksapa. Member of sustainability boards at major industrial groups and impact investment committees. Drawing on 25 years of experience working with multinationals, mid-size and small businesses across value chains, governments, and international organizations, Farid Baddache focuses on integrating human rights, climate, and ESG governance as drivers of business resilience and competitiveness. Author of several books on sustainability and responsible business. Connect on Bluesky @faridbaddache.bsky.social","sameAs":["http:\/\/www.ksapa.org","https:\/\/x.com\/Fbaddache"],"url":"https:\/\/ksapa.org\/fr\/author\/faridb\/"}]}},"_links":{"self":[{"href":"https:\/\/ksapa.org\/fr\/wp-json\/wp\/v2\/posts\/320","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ksapa.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ksapa.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ksapa.org\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ksapa.org\/fr\/wp-json\/wp\/v2\/comments?post=320"}],"version-history":[{"count":1,"href":"https:\/\/ksapa.org\/fr\/wp-json\/wp\/v2\/posts\/320\/revisions"}],"predecessor-version":[{"id":3168,"href":"https:\/\/ksapa.org\/fr\/wp-json\/wp\/v2\/posts\/320\/revisions\/3168"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ksapa.org\/fr\/wp-json\/wp\/v2\/media\/213"}],"wp:attachment":[{"href":"https:\/\/ksapa.org\/fr\/wp-json\/wp\/v2\/media?parent=320"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ksapa.org\/fr\/wp-json\/wp\/v2\/categories?post=320"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ksapa.org\/fr\/wp-json\/wp\/v2\/tags?post=320"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}