{"id":7146,"date":"2023-01-05T23:18:56","date_gmt":"2023-01-05T22:18:56","guid":{"rendered":"https:\/\/ksapa.org\/fr\/?p=7146"},"modified":"2025-10-06T14:50:24","modified_gmt":"2025-10-06T13:50:24","slug":"3-bonnes-resolutions-pour-aborder-2023-avec-optimisme","status":"publish","type":"post","link":"https:\/\/ksapa.org\/fr\/3-bonnes-resolutions-pour-aborder-2023-avec-optimisme\/","title":{"rendered":"3 bonnes r\u00e9solutions pour aborder 2023 avec optimisme"},"content":{"rendered":"\n<p><strong>Abordons l\u2019ann\u00e9e 2023 avec optimisme. Car 2022 a finalement produit son lot de bonnes surprises dont il convient d\u2019appr\u00e9cier le verre \u00e0 moiti\u00e9 plein plut\u00f4t que de se morfondre \u00e0 critiquer le verre \u00e0 moiti\u00e9 vide. Apr\u00e8s tout\u202f:\u00a0<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Fin 2022, lors de la conf\u00e9rence mondiale sur la biodiversit\u00e9 (<a href=\"https:\/\/news.un.org\/fr\/story\/2022\/12\/1130767\" target=\"_blank\" rel=\"noreferrer noopener\">COP15<\/a>), \u00e0 Montr\u00e9al, les pays sont parvenus \u00e0 adopter <a href=\"https:\/\/www.cbd.int\/conferences\/2021-2022\/cop-15\/documents\" target=\"_blank\" rel=\"noreferrer noopener\">un nouveau cadre global visant \u00e0\u202fenrayer l\u2019effondrement du vivant<\/a> d\u2019ici \u00e0 2030. Et cet accord, bien qu\u2019incomplet par ses angles morts, son caract\u00e8re peu contraignant ou son financement, \u00e9tait tout de m\u00eame inesp\u00e9r\u00e9 au vu de l\u2019\u00e9tat des n\u00e9gociations \u00e0 son ouverture entre les presque 200 nations pr\u00e9sentes.\u202fRappelons que son \u00e9quivalent pour le climat, la COP27, accouchait en Egypte d\u2019un <a href=\"https:\/\/ksapa.org\/fr\/cop-27-3-enseignements-pour-entreprises-et-investisseurs\/\" target=\"_blank\" rel=\"noreferrer noopener\">accord pour cr\u00e9er un fonds pour les d\u00e9g\u00e2ts irr\u00e9versibles<\/a> caus\u00e9s par le r\u00e9chauffement. Les pays ont \u00e9galement entam\u00e9 des n\u00e9gociations pour \u00e9laborer un trait\u00e9 international juridiquement contraignant <a href=\"https:\/\/www.unep.org\/fr\/actualites-et-recits\/recit\/coup-denvoi-des-negociations-visant-mettre-fin-la-pollution-plastique\" target=\"_blank\" rel=\"noreferrer noopener\">visant \u00e0 mettre fin \u00e0 la pollution plastique<\/a>&nbsp;<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Dans le m\u00eame temps, l\u2019Union europ\u00e9enne (UE) d\u00e9crochait une s\u00e9rie d\u2019accords pour acc\u00e9l\u00e9rer ses baisses d\u2019\u00e9missions de gaz \u00e0 effet de serre\u202f: <a href=\"https:\/\/www.europarl.europa.eu\/news\/fr\/press-room\/20221212IPR64527\/accord-sur-un-systeme-d-echange-de-quotas-d-emission-plus-ambitieux\" target=\"_blank\" rel=\"noreferrer noopener\">la r\u00e9forme de son march\u00e9 carbone<\/a>, l\u2019instauration d\u2019une <a href=\"https:\/\/www.europarl.europa.eu\/news\/fr\/press-room\/20220516IPR29647\/cbam-meps-push-for-higher-ambition-in-new-carbon-leakage-instrument\" target=\"_blank\" rel=\"noreferrer noopener\">taxe carbone aux fronti\u00e8res<\/a> ou encore l\u2019arr\u00eat de la vente de v\u00e9hicules thermiques neufs en\u202f2035. Elle s\u2019est \u00e9galement accord\u00e9e <a href=\"https:\/\/www.consilium.europa.eu\/en\/press\/press-releases\/2022\/12\/06\/council-and-parliament-strike-provisional-deal-to-cut-down-deforestation-worldwide\/\" target=\"_blank\" rel=\"noreferrer noopener\">pour interdire l\u2019importation de produits li\u00e9s \u00e0 la d\u00e9forestation<\/a> tels que le soja, le b\u0153uf ou le cacao.&nbsp;&nbsp;<br><\/li>\n\n\n\n<li>Outre-Atlantique, les Etats-Unis ont r\u00e9ussi \u00e0 faire passer un <a href=\"https:\/\/www.cnbc.com\/2022\/07\/27\/inflation-reduction-act-climate-change-provisions.html\" target=\"_blank\" rel=\"noreferrer noopener\">Inflation Reduction<\/a> Act, un plan d\u2019investissement colossal (environ 350\u202fmilliards d\u2019euros), dans la transition bas carbone qui inqui\u00e8te d\u2019ailleurs <a href=\"https:\/\/www.cnbc.com\/2022\/11\/09\/europe-shows-a-united-front-against-bidens-inflation-reduction-act.html\" target=\"_blank\" rel=\"noreferrer noopener\">nombre de nos clients europ\u00e9ens qui voient leurs actifs industriels menac\u00e9s<\/a>.&nbsp;<\/li>\n<\/ul>\n\n\n\n<p>Ces avanc\u00e9es pour l\u2019environnement \u00e9taient loin d\u2019\u00eatre gagn\u00e9es dans un contexte de multiples crises (\u00e9nerg\u00e9tique, alimentaire, de l\u2019inflation et de la dette), et alors que la guerre en Ukraine notamment \u00e9branle le multilat\u00e9ralisme.&nbsp;&nbsp;<\/p>\n\n\n\n<p>Nous suivons ces agendas depuis plus de 20 ans. Nous avons ainsi \u00e9t\u00e9 \u00e9chaud\u00e9s par des ann\u00e9es d\u2019inaction climatique, d\u2019objectifs biodiversit\u00e9 ou z\u00e9ro d\u00e9forestation jamais atteints. Mais la prise de conscience est l\u00e0. Le contexte est porteur. Etats, entreprises et investisseurs n\u2019ont pas d\u2019autre chemin que celui de la transformation et adaptation \u00e0 cette nouvelle donne environnementale, port\u00e9e dans un souci de transition juste et de respect des droits humains pour porter la d\u00e9marche de changement autant que sa conformit\u00e9 r\u00e9glementaire. Sur ce chemin, les effets d\u2019annonce non suivis d\u2019action cr\u00e9dible seront bien \u00e9videmment insuffisants, voire incapacitants.&nbsp;&nbsp;<\/p>\n\n\n\n<p>En&nbsp; 2023, l\u2019amplification des transformations ne sera possible qu\u2019en travaillant en profondeur les syst\u00e8mes alimentaire, \u00e9nerg\u00e9tique et urbain, qui pr\u00e9sentent tous les trois les sp\u00e9cificit\u00e9s de concentrer la plupart des enjeux d\u2019\u00e9rosion de biodiversit\u00e9, de d\u00e9r\u00e8glement climatique, tout en \u00e9tant des espaces humains cl\u00e9s, o\u00f9 les questions de pauvret\u00e9 et d\u2019in\u00e9galit\u00e9s rendent les questions de respect des droits humains particuli\u00e8rement sensibles.&nbsp;&nbsp;<\/p>\n\n\n\n<p>En r\u00e9ponse, Ksapa est et s\u2019affirme toujours plus comme le partenaire strat\u00e9gique de ses clients et partenaires dans le monde avec 3 suggestions pour aborder 2023 avec optimisme\u202f:&nbsp;<\/p>\n\n\n\n<ol class=\"wp-block-list\" start=\"1\">\n<li><strong>Clarifier encore et toujours le \u201cBusiness case\u00a0\u00bb&nbsp;<\/strong><\/li>\n<\/ol>\n\n\n\n<p>Les th\u00e9matiques environnementales, sociales et \u00e9thiques qui sont au c\u0153ur de l\u2019agenda de Ksapa sont trop importantes pour \u00eatre instrumentalis\u00e9es de quelle que mani\u00e8re que ce soit. Ce n\u2019est pas par valeur, principe ou opinion qu\u2019il faut ancrer ces r\u00e9flexions au c\u0153ur de tout projet \u00e9conomique, mais parce que ces th\u00e9matiques nourrissent intrins\u00e8quement la performance de ces projets \u00e9conomiques.&nbsp;&nbsp;<\/p>\n\n\n\n<p><a href=\"https:\/\/ksapa.org\/fr\/conseiller\/\">Les services de conseil de Ksapa<\/a> permettant d\u2019apporter m\u00e9thodologies et expertises en mati\u00e8re de strat\u00e9gie ESG, droits humains, climat, engagement de parties prenantes, achats responsables et finance durable et \u00e0 impact. <a href=\"https:\/\/ksapa.org\/fr\/a-propos\/etudes-de-cas-du-defi-esg-vers-la-transformation-odd-durable\/\">Ils sont d\u00e9ploy\u00e9s aux c\u00f4t\u00e9s de nos clients<\/a> pour cr\u00e9er de l\u2019alignement autour d\u2019un \u00ab\u202fbusiness case\u202f\u00bb concret, cr\u00e9ateur de valeurs, d\u00e9passant les cycles et les individualit\u00e9s dans les organisations.\u00a0<\/p>\n\n\n\n<ol class=\"wp-block-list\" start=\"2\">\n<li><strong>Concevoir et d\u00e9ployer des programmes holistiques et multi-parties prenantes sur ses priorit\u00e9s strat\u00e9giques&nbsp;<\/strong><\/li>\n<\/ol>\n\n\n\n<p>Les syst\u00e8mes alimentaire, \u00e9nerg\u00e9tique et urbain au c\u0153ur des transformations environnementales et sociales devenues imp\u00e9ratives exigent des approches holistiques et multi-parties prenantes. <a href=\"https:\/\/ksapa.org\/fr\/activer\/\">Ksapa travaille aux c\u00f4t\u00e9s de ses clients \u00e0 cet effet en apportant tout particuli\u00e8rement des outils digitaux et financiers permettant d\u2019embrasser une complexit\u00e9 de th\u00e9matiques et f\u00e9d\u00e9rer une diversit\u00e9 d\u2019int\u00e9r\u00eats dans des programmes op\u00e9rationnels de terrain<\/a>, ancr\u00e9s dans la r\u00e9alit\u00e9 des territoires partout dans le monde.\u00a0<\/p>\n\n\n\n<ol class=\"wp-block-list\" start=\"3\">\n<li><strong>Cr\u00e9er de l\u2019alignement entre parties prenantes sur ces questions complexes.&nbsp;<\/strong>&nbsp;<\/li>\n<\/ol>\n\n\n\n<p>Ksapa op\u00e9rant en entreprise \u00e0 mission, nos \u00e9quipes partagent et animent tout au long de l\u2019ann\u00e9e diff\u00e9rentes r\u00e9flexions aupr\u00e8s d\u2019\u00e9cosyst\u00e8mes complexes de parties prenantes. Nous allons ainsi par exemple travailler avec France Invest tout au long de l\u2019ann\u00e9e 2023 aupr\u00e8s du Groupe de Travail \u00ab\u202fDroits Humains\u202f\u00bb pour aider cette communaut\u00e9 financi\u00e8re \u00e0 s\u2019aligner sur des approches assurant la bonne prise en compte de ces enjeux complexes dans leurs processus de d\u00e9cision d\u2019investissement, en conformit\u00e9 avec un faisceau r\u00e9glementaire convergent poussant \u00e0 renforcer les m\u00e9thodologies et les expertises.\u00a0<\/p>\n\n\n\n<p>Ksapa reste plus que jamais un catalyseur international producteur de solutions concr\u00e8tes et innovantes pour une transition plus juste, plus durable, plus rapide.\u00a0Rejoignez notre mouvement !<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Abordons l\u2019ann\u00e9e 2023 avec optimisme. Car 2022 a finalement produit son lot de bonnes surprises dont il convient d\u2019appr\u00e9cier le verre \u00e0 moiti\u00e9 plein plut\u00f4t que de se morfondre \u00e0 critiquer le verre \u00e0 moiti\u00e9 vide. <\/p>\n","protected":false},"author":2,"featured_media":7149,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2683,10,11,2696,215,2691,20,2914],"tags":[136,404,148],"class_list":["post-7146","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-changement-climatique","category-developpement-durable","category-droits-de-lhomme","category-finance-durable-esg","category-impact","category-objectifs-de-developpement-durable-odd","category-rse","category-transition-energetique","tag-competitivite","tag-odd-objectifs-de-developpement-durable","tag-rse"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>3 bonnes r\u00e9solutions pour aborder 2023 avec optimisme<\/title>\n<meta name=\"description\" content=\"Abordons l\u2019ann\u00e9e 2023 avec optimisme. Car 2022 a finalement produit son lot de bonnes surprises dont il convient d\u2019appr\u00e9cier le verre \u00e0 moiti\u00e9 plein plut\u00f4t que de se morfondre \u00e0 critiquer le verre \u00e0 moiti\u00e9 vide.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ksapa.org\/fr\/3-bonnes-resolutions-pour-aborder-2023-avec-optimisme\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"3 bonnes r\u00e9solutions pour aborder 2023 avec optimisme\" \/>\n<meta property=\"og:description\" content=\"Abordons l\u2019ann\u00e9e 2023 avec optimisme. Car 2022 a finalement produit son lot de bonnes surprises dont il convient d\u2019appr\u00e9cier le verre \u00e0 moiti\u00e9 plein plut\u00f4t que de se morfondre \u00e0 critiquer le verre \u00e0 moiti\u00e9 vide.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ksapa.org\/fr\/3-bonnes-resolutions-pour-aborder-2023-avec-optimisme\/\" \/>\n<meta property=\"og:site_name\" content=\"Ksapa - fr\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-05T22:18:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-06T13:50:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ksapa.org\/fr\/wp-content\/uploads\/sites\/1\/2023\/01\/Carte-de-voeux-2023-KSAPA-gif.gif\" \/>\n\t<meta property=\"og:image:width\" content=\"1020\" \/>\n\t<meta property=\"og:image:height\" content=\"574\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/gif\" \/>\n<meta name=\"author\" content=\"Farid Baddache\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Fbaddache\" \/>\n<meta name=\"twitter:site\" content=\"@KsapaOrg\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Farid Baddache\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/3-bonnes-resolutions-pour-aborder-2023-avec-optimisme\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/3-bonnes-resolutions-pour-aborder-2023-avec-optimisme\\\/\"},\"author\":{\"name\":\"Farid Baddache\",\"@id\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/#\\\/schema\\\/person\\\/04c46158d370e75b9ece9fe70d969403\"},\"headline\":\"3 bonnes r\u00e9solutions pour aborder 2023 avec optimisme\",\"datePublished\":\"2023-01-05T22:18:56+00:00\",\"dateModified\":\"2025-10-06T13:50:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/3-bonnes-resolutions-pour-aborder-2023-avec-optimisme\\\/\"},\"wordCount\":962,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/3-bonnes-resolutions-pour-aborder-2023-avec-optimisme\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/1\\\/2023\\\/01\\\/Carte-de-voeux-2023-KSAPA-gif.gif\",\"keywords\":[\"Comp\u00e9titivit\u00e9\",\"ODD - Objectifs de D\u00e9veloppement Durable\",\"RSE\"],\"articleSection\":[\"Changement climatique\",\"D\u00e9veloppement Durable\",\"Droits de l'Homme\",\"Finance Durable et ESG\",\"Impact\",\"Objectifs de D\u00e9veloppement Durable (ODD)\",\"Responsabilit\u00e9 Soci\u00e9tale et Environnementale (RSE)\",\"Transition \u00e9nerg\u00e9tique\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/ksapa.org\\\/fr\\\/3-bonnes-resolutions-pour-aborder-2023-avec-optimisme\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/3-bonnes-resolutions-pour-aborder-2023-avec-optimisme\\\/\",\"url\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/3-bonnes-resolutions-pour-aborder-2023-avec-optimisme\\\/\",\"name\":\"3 bonnes r\u00e9solutions pour aborder 2023 avec optimisme\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/3-bonnes-resolutions-pour-aborder-2023-avec-optimisme\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/3-bonnes-resolutions-pour-aborder-2023-avec-optimisme\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/1\\\/2023\\\/01\\\/Carte-de-voeux-2023-KSAPA-gif.gif\",\"datePublished\":\"2023-01-05T22:18:56+00:00\",\"dateModified\":\"2025-10-06T13:50:24+00:00\",\"description\":\"Abordons l\u2019ann\u00e9e 2023 avec optimisme. Car 2022 a finalement produit son lot de bonnes surprises dont il convient d\u2019appr\u00e9cier le verre \u00e0 moiti\u00e9 plein plut\u00f4t que de se morfondre \u00e0 critiquer le verre \u00e0 moiti\u00e9 vide.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/3-bonnes-resolutions-pour-aborder-2023-avec-optimisme\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ksapa.org\\\/fr\\\/3-bonnes-resolutions-pour-aborder-2023-avec-optimisme\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/3-bonnes-resolutions-pour-aborder-2023-avec-optimisme\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/1\\\/2023\\\/01\\\/Carte-de-voeux-2023-KSAPA-gif.gif\",\"contentUrl\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/1\\\/2023\\\/01\\\/Carte-de-voeux-2023-KSAPA-gif.gif\",\"width\":1280,\"height\":720,\"caption\":\"3 bonnes r\u00e9solutions pour aborder 2023 avec optimisme\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/3-bonnes-resolutions-pour-aborder-2023-avec-optimisme\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"3 bonnes r\u00e9solutions pour aborder 2023 avec optimisme\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/\",\"name\":\"Ksapa - fr\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/#organization\",\"name\":\"ksapa\",\"url\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/1\\\/2019\\\/06\\\/icone-ksapa.jpg\",\"contentUrl\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/1\\\/2019\\\/06\\\/icone-ksapa.jpg\",\"width\":\"442\",\"height\":\"421\",\"caption\":\"ksapa\"},\"image\":{\"@id\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/KsapaOrg\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/#\\\/schema\\\/person\\\/04c46158d370e75b9ece9fe70d969403\",\"name\":\"Farid Baddache\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/1\\\/2019\\\/02\\\/farid-baddache-blog-auteur-resilience-impact-inclusion.jpg\",\"url\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/1\\\/2019\\\/02\\\/farid-baddache-blog-auteur-resilience-impact-inclusion.jpg\",\"contentUrl\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/1\\\/2019\\\/02\\\/farid-baddache-blog-auteur-resilience-impact-inclusion.jpg\",\"caption\":\"Farid Baddache\"},\"description\":\"CEO and Co-Founder of Ksapa. Member of sustainability boards at major industrial groups and impact investment committees. Drawing on 25 years of experience working with multinationals, mid-size and small businesses across value chains, governments, and international organizations, Farid Baddache focuses on integrating human rights, climate, and ESG governance as drivers of business resilience and competitiveness. Author of several books on sustainability and responsible business. Connect on Bluesky @faridbaddache.bsky.social\",\"sameAs\":[\"http:\\\/\\\/www.ksapa.org\",\"https:\\\/\\\/x.com\\\/Fbaddache\"],\"url\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/author\\\/faridb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"3 bonnes r\u00e9solutions pour aborder 2023 avec optimisme","description":"Abordons l\u2019ann\u00e9e 2023 avec optimisme. Car 2022 a finalement produit son lot de bonnes surprises dont il convient d\u2019appr\u00e9cier le verre \u00e0 moiti\u00e9 plein plut\u00f4t que de se morfondre \u00e0 critiquer le verre \u00e0 moiti\u00e9 vide.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ksapa.org\/fr\/3-bonnes-resolutions-pour-aborder-2023-avec-optimisme\/","og_locale":"fr_FR","og_type":"article","og_title":"3 bonnes r\u00e9solutions pour aborder 2023 avec optimisme","og_description":"Abordons l\u2019ann\u00e9e 2023 avec optimisme. Car 2022 a finalement produit son lot de bonnes surprises dont il convient d\u2019appr\u00e9cier le verre \u00e0 moiti\u00e9 plein plut\u00f4t que de se morfondre \u00e0 critiquer le verre \u00e0 moiti\u00e9 vide.","og_url":"https:\/\/ksapa.org\/fr\/3-bonnes-resolutions-pour-aborder-2023-avec-optimisme\/","og_site_name":"Ksapa - fr","article_published_time":"2023-01-05T22:18:56+00:00","article_modified_time":"2025-10-06T13:50:24+00:00","og_image":[{"url":"https:\/\/ksapa.org\/fr\/wp-content\/uploads\/sites\/1\/2023\/01\/Carte-de-voeux-2023-KSAPA-gif.gif","width":1020,"height":574,"type":"image\/gif"}],"author":"Farid Baddache","twitter_card":"summary_large_image","twitter_creator":"@Fbaddache","twitter_site":"@KsapaOrg","twitter_misc":{"\u00c9crit par":"Farid Baddache","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ksapa.org\/fr\/3-bonnes-resolutions-pour-aborder-2023-avec-optimisme\/#article","isPartOf":{"@id":"https:\/\/ksapa.org\/fr\/3-bonnes-resolutions-pour-aborder-2023-avec-optimisme\/"},"author":{"name":"Farid Baddache","@id":"https:\/\/ksapa.org\/fr\/#\/schema\/person\/04c46158d370e75b9ece9fe70d969403"},"headline":"3 bonnes r\u00e9solutions pour aborder 2023 avec optimisme","datePublished":"2023-01-05T22:18:56+00:00","dateModified":"2025-10-06T13:50:24+00:00","mainEntityOfPage":{"@id":"https:\/\/ksapa.org\/fr\/3-bonnes-resolutions-pour-aborder-2023-avec-optimisme\/"},"wordCount":962,"commentCount":0,"publisher":{"@id":"https:\/\/ksapa.org\/fr\/#organization"},"image":{"@id":"https:\/\/ksapa.org\/fr\/3-bonnes-resolutions-pour-aborder-2023-avec-optimisme\/#primaryimage"},"thumbnailUrl":"https:\/\/ksapa.org\/fr\/wp-content\/uploads\/sites\/1\/2023\/01\/Carte-de-voeux-2023-KSAPA-gif.gif","keywords":["Comp\u00e9titivit\u00e9","ODD - Objectifs de D\u00e9veloppement Durable","RSE"],"articleSection":["Changement climatique","D\u00e9veloppement Durable","Droits de l'Homme","Finance Durable et ESG","Impact","Objectifs de D\u00e9veloppement Durable (ODD)","Responsabilit\u00e9 Soci\u00e9tale et Environnementale (RSE)","Transition \u00e9nerg\u00e9tique"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ksapa.org\/fr\/3-bonnes-resolutions-pour-aborder-2023-avec-optimisme\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ksapa.org\/fr\/3-bonnes-resolutions-pour-aborder-2023-avec-optimisme\/","url":"https:\/\/ksapa.org\/fr\/3-bonnes-resolutions-pour-aborder-2023-avec-optimisme\/","name":"3 bonnes r\u00e9solutions pour aborder 2023 avec optimisme","isPartOf":{"@id":"https:\/\/ksapa.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ksapa.org\/fr\/3-bonnes-resolutions-pour-aborder-2023-avec-optimisme\/#primaryimage"},"image":{"@id":"https:\/\/ksapa.org\/fr\/3-bonnes-resolutions-pour-aborder-2023-avec-optimisme\/#primaryimage"},"thumbnailUrl":"https:\/\/ksapa.org\/fr\/wp-content\/uploads\/sites\/1\/2023\/01\/Carte-de-voeux-2023-KSAPA-gif.gif","datePublished":"2023-01-05T22:18:56+00:00","dateModified":"2025-10-06T13:50:24+00:00","description":"Abordons l\u2019ann\u00e9e 2023 avec optimisme. Car 2022 a finalement produit son lot de bonnes surprises dont il convient d\u2019appr\u00e9cier le verre \u00e0 moiti\u00e9 plein plut\u00f4t que de se morfondre \u00e0 critiquer le verre \u00e0 moiti\u00e9 vide.","breadcrumb":{"@id":"https:\/\/ksapa.org\/fr\/3-bonnes-resolutions-pour-aborder-2023-avec-optimisme\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ksapa.org\/fr\/3-bonnes-resolutions-pour-aborder-2023-avec-optimisme\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/ksapa.org\/fr\/3-bonnes-resolutions-pour-aborder-2023-avec-optimisme\/#primaryimage","url":"https:\/\/ksapa.org\/fr\/wp-content\/uploads\/sites\/1\/2023\/01\/Carte-de-voeux-2023-KSAPA-gif.gif","contentUrl":"https:\/\/ksapa.org\/fr\/wp-content\/uploads\/sites\/1\/2023\/01\/Carte-de-voeux-2023-KSAPA-gif.gif","width":1280,"height":720,"caption":"3 bonnes r\u00e9solutions pour aborder 2023 avec optimisme"},{"@type":"BreadcrumbList","@id":"https:\/\/ksapa.org\/fr\/3-bonnes-resolutions-pour-aborder-2023-avec-optimisme\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ksapa.org\/fr\/"},{"@type":"ListItem","position":2,"name":"3 bonnes r\u00e9solutions pour aborder 2023 avec optimisme"}]},{"@type":"WebSite","@id":"https:\/\/ksapa.org\/fr\/#website","url":"https:\/\/ksapa.org\/fr\/","name":"Ksapa - fr","description":"","publisher":{"@id":"https:\/\/ksapa.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ksapa.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/ksapa.org\/fr\/#organization","name":"ksapa","url":"https:\/\/ksapa.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/ksapa.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/ksapa.org\/fr\/wp-content\/uploads\/sites\/1\/2019\/06\/icone-ksapa.jpg","contentUrl":"https:\/\/ksapa.org\/fr\/wp-content\/uploads\/sites\/1\/2019\/06\/icone-ksapa.jpg","width":"442","height":"421","caption":"ksapa"},"image":{"@id":"https:\/\/ksapa.org\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/KsapaOrg"]},{"@type":"Person","@id":"https:\/\/ksapa.org\/fr\/#\/schema\/person\/04c46158d370e75b9ece9fe70d969403","name":"Farid Baddache","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/ksapa.org\/fr\/wp-content\/uploads\/sites\/1\/2019\/02\/farid-baddache-blog-auteur-resilience-impact-inclusion.jpg","url":"https:\/\/ksapa.org\/fr\/wp-content\/uploads\/sites\/1\/2019\/02\/farid-baddache-blog-auteur-resilience-impact-inclusion.jpg","contentUrl":"https:\/\/ksapa.org\/fr\/wp-content\/uploads\/sites\/1\/2019\/02\/farid-baddache-blog-auteur-resilience-impact-inclusion.jpg","caption":"Farid Baddache"},"description":"CEO and Co-Founder of Ksapa. Member of sustainability boards at major industrial groups and impact investment committees. Drawing on 25 years of experience working with multinationals, mid-size and small businesses across value chains, governments, and international organizations, Farid Baddache focuses on integrating human rights, climate, and ESG governance as drivers of business resilience and competitiveness. Author of several books on sustainability and responsible business. Connect on Bluesky @faridbaddache.bsky.social","sameAs":["http:\/\/www.ksapa.org","https:\/\/x.com\/Fbaddache"],"url":"https:\/\/ksapa.org\/fr\/author\/faridb\/"}]}},"_links":{"self":[{"href":"https:\/\/ksapa.org\/fr\/wp-json\/wp\/v2\/posts\/7146","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ksapa.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ksapa.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ksapa.org\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ksapa.org\/fr\/wp-json\/wp\/v2\/comments?post=7146"}],"version-history":[{"count":6,"href":"https:\/\/ksapa.org\/fr\/wp-json\/wp\/v2\/posts\/7146\/revisions"}],"predecessor-version":[{"id":10868,"href":"https:\/\/ksapa.org\/fr\/wp-json\/wp\/v2\/posts\/7146\/revisions\/10868"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ksapa.org\/fr\/wp-json\/wp\/v2\/media\/7149"}],"wp:attachment":[{"href":"https:\/\/ksapa.org\/fr\/wp-json\/wp\/v2\/media?parent=7146"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ksapa.org\/fr\/wp-json\/wp\/v2\/categories?post=7146"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ksapa.org\/fr\/wp-json\/wp\/v2\/tags?post=7146"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}