{"id":7364,"date":"2023-03-14T17:07:50","date_gmt":"2023-03-14T16:07:50","guid":{"rendered":"https:\/\/ksapa.org\/fr\/?p=7364"},"modified":"2025-12-03T15:41:59","modified_gmt":"2025-12-03T14:41:59","slug":"sutti-ameliore-la-vie-des-petits-producteurs-de-caoutchouc","status":"publish","type":"post","link":"https:\/\/ksapa.org\/fr\/sutti-ameliore-la-vie-des-petits-producteurs-de-caoutchouc\/","title":{"rendered":"SUTTI am\u00e9liore la vie des petits producteurs de caoutchouc"},"content":{"rendered":"\n<p>Michelin &amp; un partenaire constructeur automobile allemand s&rsquo;engagent en faveur de la culture durable du caoutchouc naturel. L&rsquo;engagement du constructeur automobile et du fabricant de pneus en faveur de la transparence et de meilleures conditions de travail dans l&rsquo;extraction des mati\u00e8res premi\u00e8res est d\u00e9montr\u00e9 par le <a href=\"https:\/\/ksapa.org\/about-us\/our-case-studies\/providing-access-to-training-to-smallholders-ksapa-case-study\/\">projet CASCADE (Committed Actions for Smallholders Capacity Development)<\/a>. Ce projet est le premier \u00e0 int\u00e9grer l&rsquo;ensemble de la cha\u00eene d&rsquo;approvisionnement : les petits exploitants agricoles et leurs partenaires, une entreprise de traitement du caoutchouc naturel, un fabricant de pneus et un constructeur automobile.<\/p>\n\n\n\n<p>Dans ce programme, Ksapa est responsable de la conception et du d\u00e9ploiement des efforts de renforcement des capacit\u00e9s en utilisant sa solution SUTTI pour soutenir les cultivateurs de caoutchouc de Sumatra. Le renforcement des capacit\u00e9s s&rsquo;articule autour de trois piliers : la productivit\u00e9 du caoutchouc, la diversification et la sensibilisation aux droits sociaux et humains. Ksapa et ses partenaires locaux ont commenc\u00e9 \u00e0 former les agriculteurs en 2021.<\/p>\n\n\n\n<p>Dans ce blog, Ksapa revient sur les r\u00e9sultats d&rsquo;une enqu\u00eate qualitative d&rsquo;impact men\u00e9e aupr\u00e8s des agriculteurs quelques mois apr\u00e8s avoir re\u00e7u une formation sur les pratiques de l&rsquo;h\u00e9v\u00e9aculture.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-projet-cascade-promouvoir-l-extraction-durable-du-caoutchouc-naturel\">Projet CASCADE : Promouvoir l&rsquo;extraction durable du caoutchouc naturel<\/h2>\n\n\n\n<p>L&rsquo;Indon\u00e9sie est l&rsquo;une des plus importantes r\u00e9gions de production de caoutchouc au monde. Michelin a identifi\u00e9 des risques de durabilit\u00e9 dans la cha\u00eene d&rsquo;approvisionnement du caoutchouc en utilisant RubberWay, une application sp\u00e9cialement d\u00e9velopp\u00e9e \u00e0 cet effet, et en menant des discussions avec les acteurs du march\u00e9. Cette \u00e9valuation des risques a permis d&rsquo;identifier la zone prioritaire de Jambi, \u00e0 Sumatra, comme point de d\u00e9part.<\/p>\n\n\n\n<p>Pour des fabricants tel que Michelin, le caoutchouc est une mati\u00e8re premi\u00e8re essentielle, car il est utilis\u00e9 dans de nombreuses pi\u00e8ces de leurs produits. C&rsquo;est pourquoi <a href=\"https:\/\/ksapa.org\/supporting-indonesian-rubber-plantation-farmers-with-porsche-and-michelin\/\">Michelin et son partenaire de longue date, se sont engag\u00e9s \u00e0 soutenir les petits planteurs de Sumatra<\/a> dans l&rsquo;extraction du caoutchouc, en collaboration avec Ksapa. Gr\u00e2ce au renforcement des capacit\u00e9s, \u00e0 la diversification des exploitations et \u00e0 l&rsquo;\u00e9ducation \u00e0 la biodiversit\u00e9, l&rsquo;objectif est d&rsquo;am\u00e9liorer \u00e0 long terme les moyens de subsistance des petits exploitants indon\u00e9siens.<\/p>\n\n\n\n<p>\u00c0 ce titre, CASCADE est l&rsquo;un des premiers projets au monde \u00e0 commencer au premier kilom\u00e8tre de la cha\u00eene d&rsquo;approvisionnement en caoutchouc naturel. Le projet vise \u00e0 former 1 000 petits exploitants par l&rsquo;interm\u00e9diaire de partenaires locaux afin de rendre les m\u00e9thodes d&rsquo;extraction plus respectueuses de l&rsquo;environnement et plus efficaces.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-soutenir-les-petits-exploitants-agricoles-grace-a-la-solution-sutti-de-ksapa\">Soutenir les petits exploitants agricoles gr\u00e2ce \u00e0 la solution SUTTI de Ksapa<\/h2>\n\n\n\n<p>Ksapa utilise sa <a href=\"https:\/\/ksapa.org\/activate\/sutti-scale-up-training-traceability-impact\/\">solution SUTTI<\/a> pour calibrer et d\u00e9ployer CASCADE. SUTTI est un programme d&rsquo;impact \u00e0 grande \u00e9chelle qui s&rsquo;appuie sur un mod\u00e8le hybride de renforcement des capacit\u00e9s. Nous combinons en effet de la formation en pr\u00e9sentiel et des solutions num\u00e9riques pour renforcer la formation des travailleurs et contr\u00f4ler notre impact dans le processus.<\/p>\n\n\n\n<p>Notre objectif est de cr\u00e9er un impact durable et concret \u00e0 grande \u00e9chelle :<\/p>\n\n\n\n<p>&#8211; En apportant aux petits exploitants un savoir-faire, un changement de pratiques, une augmentation des revenus, une diversification des activit\u00e9s et des connaissances financi\u00e8res.<\/p>\n\n\n\n<p>&#8211; En am\u00e9liorant et en garantissant des politiques d&rsquo;approvisionnement responsables.<\/p>\n\n\n\n<p>&#8211; En \u00e9laborant des mod\u00e8les \u00e9conomiques performants et impactant pour d\u00e9velopper les programmes.<\/p>\n\n\n\n<p>En outre, la <a href=\"https:\/\/ksapa.org\/activate\/sutti-digital-solution\/\">suite num\u00e9rique SUTTI<\/a> de Ksapa maximise l&rsquo;acc\u00e8s \u00e0 la formation par le biais d&rsquo;un outil d&rsquo;apprentissage en ligne et de suivit de l&rsquo;impact du programme par rapport aux objectifs de performance sociale, environnementale et \u00e9conomique. Cela aide les groupes industriels \u00e0 mieux comprendre leur carte d&rsquo;approvisionnement et permet aux petits exploitants de contr\u00f4ler leur ferme.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"549\" height=\"367\" src=\"https:\/\/ksapa.org\/fr\/wp-content\/uploads\/sites\/1\/2023\/03\/image.png\" alt=\"\" class=\"wp-image-7365\" \/><figcaption class=\"wp-element-caption\">Suite applicative \u00e0 destination des fermiers<\/figcaption><\/figure>\n<\/div>\n\n\n<h2 class=\"wp-block-heading\" id=\"h-impact-de-cascade-apprentissages-centres-sur-les-besoins-de-l-agriculteur-pour-des-impacts-directs\">Impact de CASCADE : Apprentissages centr\u00e9s sur les besoins de l\u2019agriculteur pour des impacts directs<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-une-methodologie-centree-sur-l-agriculteur-pour-une-plus-grande-satisfaction\"><strong>UNE M\u00c9THODOLOGIE CENTR\u00c9E SUR L&rsquo;AGRICULTEUR POUR UNE PLUS GRANDE SATISFACTION<\/strong><\/h3>\n\n\n\n<p>SUTTI est premi\u00e8rement con\u00e7u pour permettre aux petits producteurs d&rsquo;atteindre une plus grande r\u00e9silience en dispensant une formation professionnelle sur des sujets prioritaires allant des comp\u00e9tences agricoles \u00e0 la sant\u00e9 et \u00e0 la s\u00e9curit\u00e9, en passant par la biodiversit\u00e9, etc. La formation dispens\u00e9e repose sur une compr\u00e9hension approfondie des besoins fondamentaux des petits exploitants. Ce diagnostic et cette analyse \u00e0 360 degr\u00e9s centr\u00e9s sur l&rsquo;agriculteur sont fondamentaux pour la bonne mise en \u0153uvre des projets SUTTI.<\/p>\n\n\n\n<p>En effet, gr\u00e2ce \u00e0 la phase de diagnostic, Ksapa identifie et classe les interventions en tant que gains rapides (\u00ab&nbsp;quick wins&nbsp;\u00bb) ou interventions \u00e0 moyen terme. Les gains rapides sont des actions dont la mise en \u0153uvre par les agriculteurs ne n\u00e9cessite pas beaucoup de temps ou d&rsquo;investissement et qui apportent des b\u00e9n\u00e9fices dans un court laps de temps. Il est essentiel de commencer le processus de renforcement des capacit\u00e9s par des actions \u00e0 effet rapide permettant d&rsquo;instaurer la confiance avec les agriculteurs, puis d&rsquo;engager des strat\u00e9gies plus complexes.<\/p>\n\n\n\n<p>La premi\u00e8re formation dispens\u00e9e par Ksapa et son partenaire local est donc bas\u00e9e sur les pratiques de culture de l&rsquo;h\u00e9v\u00e9a apportant des impacts rapides. Le r\u00e9sultat de l&rsquo;enqu\u00eate &#8211; men\u00e9e aupr\u00e8s de 95% des agriculteurs (250) ayant re\u00e7u une formation 6 mois auparavant &#8211; est que 82% d&rsquo;entre eux sont satisfaits ou tr\u00e8s satisfaits de la formation. Ce r\u00e9sultat doit \u00e9galement \u00eatre consid\u00e9r\u00e9 en comparaison avec les programmes de formation traditionnels qui ont g\u00e9n\u00e9ralement un taux de satisfaction de 50 \u00e0 60% maximum.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"472\" height=\"344\" src=\"https:\/\/ksapa.org\/fr\/wp-content\/uploads\/sites\/1\/2023\/03\/image-1.png\" alt=\"\" class=\"wp-image-7366\" \/><\/figure>\n<\/div>\n\n\n<h3 class=\"wp-block-heading\" id=\"h-une-methodologie-de-formation-unique-pour-des-impacts-concrets\"><strong>UNE M\u00c9THODOLOGIE DE FORMATION UNIQUE POUR DES IMPACTS CONCRETS<\/strong><\/h3>\n\n\n\n<p>L&rsquo;approche de la formation de Ksapa a notamment \u00e9t\u00e9 salu\u00e9e par les agriculteurs interrog\u00e9s dans le cadre de l&rsquo;enqu\u00eate.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"886\" height=\"342\" src=\"https:\/\/ksapa.org\/fr\/wp-content\/uploads\/sites\/1\/2023\/03\/image-2.png\" alt=\"\" class=\"wp-image-7367\" srcset=\"https:\/\/ksapa.org\/fr\/wp-content\/uploads\/sites\/1\/2023\/03\/image-2.png 886w, https:\/\/ksapa.org\/fr\/wp-content\/uploads\/sites\/1\/2023\/03\/image-2-800x309.png 800w, https:\/\/ksapa.org\/fr\/wp-content\/uploads\/sites\/1\/2023\/03\/image-2-768x296.png 768w\" sizes=\"(max-width: 886px) 100vw, 886px\" \/><\/figure>\n<\/div>\n\n\n<p>En effet, la combinaison d&rsquo;un contenu de formation adapt\u00e9 et d&rsquo;une p\u00e9dagogie ad\u00e9quate avec des capacit\u00e9s d&rsquo;apprentissage en ligne s&rsquo;est av\u00e9r\u00e9e d\u00e9cisive sur l&rsquo;adoption des pratiques par les agriculteurs. En travaillant conjointement avec les partenaires locaux et Michelin, Ksapa a \u00e9t\u00e9 en mesure d&rsquo;\u00e9laborer un contenu facile \u00e0 comprendre et pertinent pour les agriculteurs. Le fait d&rsquo;offrir des formations dans un format hybride, en utilisant des moyens pr\u00e9sentiels et num\u00e9riques, a \u00e9galement permis aux agriculteurs d&rsquo;approfondir continuellement les pratiques pour une adoption maximale.<\/p>\n\n\n\n<p>La pertinence des enseignements dispens\u00e9s a aid\u00e9 les agriculteurs \u00e0 relever des d\u00e9fis qui n&rsquo;avaient pas \u00e9t\u00e9 r\u00e9solus. Ainsi, les pratiques diffus\u00e9es ont eu un impact important sur les agriculteurs qui ont rapidement compris la valeur de ces formations. En cons\u00e9quence, 96,5 % des agriculteurs ont appliqu\u00e9 au moins une des pratiques pr\u00e9sent\u00e9es.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"768\" height=\"231\" src=\"https:\/\/ksapa.org\/fr\/wp-content\/uploads\/sites\/1\/2023\/03\/image-3.png\" alt=\"\" class=\"wp-image-7368\" \/><\/figure>\n<\/div>\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"1063\" height=\"333\" src=\"https:\/\/ksapa.org\/fr\/wp-content\/uploads\/sites\/1\/2023\/03\/image-4.png\" alt=\"\" class=\"wp-image-7369\" srcset=\"https:\/\/ksapa.org\/fr\/wp-content\/uploads\/sites\/1\/2023\/03\/image-4.png 1063w, https:\/\/ksapa.org\/fr\/wp-content\/uploads\/sites\/1\/2023\/03\/image-4-800x251.png 800w, https:\/\/ksapa.org\/fr\/wp-content\/uploads\/sites\/1\/2023\/03\/image-4-768x241.png 768w\" sizes=\"(max-width: 1063px) 100vw, 1063px\" \/><\/figure>\n<\/div>\n\n\n<p>Les agriculteurs appliquant ces pratiques ont eu l&rsquo;occasion de constater par eux-m\u00eames les impacts positifs induits apr\u00e8s quelques mois. Alors que ce premier groupe de formation se concentrait sur la culture du caoutchouc et la productivit\u00e9, nous avons observ\u00e9 que les agriculteurs ont fait \u00e9tat d&rsquo;impacts multiples \u00e0 travers diff\u00e9rentes dimensions : \u00e9conomique, agronomique, sant\u00e9&#8230; Cette premi\u00e8re \u00e9tude d&rsquo;impact qualitative prouve donc une fois de plus l&rsquo;int\u00e9r\u00eat de ces pratiques \u00e0 impact rapide pour les agriculteurs.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"1063\" height=\"316\" src=\"https:\/\/ksapa.org\/fr\/wp-content\/uploads\/sites\/1\/2023\/03\/image-5.png\" alt=\"\" class=\"wp-image-7370\" srcset=\"https:\/\/ksapa.org\/fr\/wp-content\/uploads\/sites\/1\/2023\/03\/image-5.png 1063w, https:\/\/ksapa.org\/fr\/wp-content\/uploads\/sites\/1\/2023\/03\/image-5-800x238.png 800w, https:\/\/ksapa.org\/fr\/wp-content\/uploads\/sites\/1\/2023\/03\/image-5-768x228.png 768w\" sizes=\"(max-width: 1063px) 100vw, 1063px\" \/><\/figure>\n<\/div>\n\n\n<p>En particulier, de nombreux agriculteurs ont signal\u00e9 une am\u00e9lioration du rendement rapidement apr\u00e8s la formation. Dans une question sp\u00e9cifique, 90 % des agriculteurs ont d\u00e9clar\u00e9 avoir constat\u00e9 une augmentation des rendements, avec une augmentation moyenne de 10 %. Ces gains rapides sont essentiels pour les agriculteurs, car ils constituent la premi\u00e8re \u00e9tape de l&rsquo;am\u00e9lioration de leurs moyens de subsistance. Les effets combin\u00e9s, tels que l&rsquo;augmentation des rendements et la r\u00e9duction de l&rsquo;utilisation d&rsquo;intrants, am\u00e9liorent encore la rentabilit\u00e9 de leurs exploitations.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-conclusion\">Conclusion<\/h2>\n\n\n\n<p>Michelin et Porsche, en tant que leaders de l&rsquo;industrie, ont confi\u00e9 leurs efforts de d\u00e9veloppement durable \u00e0 Ksapa et \u00e0 sa solution SUTTI. En tant que mati\u00e8re premi\u00e8re cl\u00e9 dans de nombreux produits, la performance ESG des cha\u00eenes d&rsquo;approvisionnement en caoutchouc naturel doit \u00eatre am\u00e9lior\u00e9e. En particulier, dans certaines zones de culture telles que Jambi \u00e0 Sumatra, les agriculteurs sont confront\u00e9s \u00e0 de nombreux d\u00e9fis sociaux, \u00e9conomiques et agronomiques.<\/p>\n\n\n\n<p>Dans le cadre d&rsquo;un processus de cod\u00e9veloppement avec des partenaires locaux et industriels, Ksapa a d\u00e9velopp\u00e9 un contenu de formation pertinent et adapt\u00e9 qui sera diffus\u00e9 dans le cadre du projet CASCADE. En dispensant des formations par le biais d&rsquo;une m\u00e9thodologie hybride combinant le face-\u00e0-face et le num\u00e9rique, Ksapa souhaitait obtenir un retour d&rsquo;information sur ses m\u00e9thodologies. En ce sens, cette premi\u00e8re \u00e9valuation qualitative de l&rsquo;impact a clairement prouv\u00e9 le bien-fond\u00e9 de ses m\u00e9thodes de formation et de son approche centr\u00e9e sur l&rsquo;agriculteur. En s&rsquo;appuyant sur les premiers impacts observ\u00e9s et les gains rapides, Ksapa et ses partenaires continueront \u00e0 travailler avec les agriculteurs pour apporter de la valeur et de l&rsquo;impact \u00e0 plus grande \u00e9chelle.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>D\u00e9couvrez les impacts positifs du programme hybride de Ksapa de formation \u00e0 l&rsquo;h\u00e9v\u00e9aculture sur les producteurs de caoutchouc indon\u00e9siens <\/p>\n","protected":false},"author":75,"featured_media":7372,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2687,215,2697],"tags":[2815],"class_list":["post-7364","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-achats-responsables","category-impact","category-paysans-du-sud","tag-sutti"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Impact social : Former les producteurs de caoutchouc en Indon\u00e9sie<\/title>\n<meta name=\"description\" content=\"D\u00e9couvrez les impacts positifs du programme hybride de Ksapa de formation \u00e0 l&#039;h\u00e9v\u00e9aculture sur les producteurs de caoutchouc indon\u00e9siens\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ksapa.org\/fr\/sutti-ameliore-la-vie-des-petits-producteurs-de-caoutchouc\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Impact social : Former les producteurs de caoutchouc en Indon\u00e9sie\" \/>\n<meta property=\"og:description\" content=\"D\u00e9couvrez les impacts positifs du programme hybride de Ksapa de formation \u00e0 l&#039;h\u00e9v\u00e9aculture sur les producteurs de caoutchouc indon\u00e9siens\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ksapa.org\/fr\/sutti-ameliore-la-vie-des-petits-producteurs-de-caoutchouc\/\" \/>\n<meta property=\"og:site_name\" content=\"Ksapa - fr\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-14T16:07:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-03T14:41:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ksapa.org\/fr\/wp-content\/uploads\/sites\/1\/2023\/03\/R0000039-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Adrien Covo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@KsapaOrg\" \/>\n<meta name=\"twitter:site\" content=\"@KsapaOrg\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Adrien Covo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/sutti-ameliore-la-vie-des-petits-producteurs-de-caoutchouc\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/sutti-ameliore-la-vie-des-petits-producteurs-de-caoutchouc\\\/\"},\"author\":{\"name\":\"Adrien Covo\",\"@id\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/#\\\/schema\\\/person\\\/5c5037e344a16220951fc1019696033f\"},\"headline\":\"SUTTI am\u00e9liore la vie des petits producteurs de caoutchouc\",\"datePublished\":\"2023-03-14T16:07:50+00:00\",\"dateModified\":\"2025-12-03T14:41:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/sutti-ameliore-la-vie-des-petits-producteurs-de-caoutchouc\\\/\"},\"wordCount\":1520,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/sutti-ameliore-la-vie-des-petits-producteurs-de-caoutchouc\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/1\\\/2023\\\/03\\\/R0000039-scaled.jpg\",\"keywords\":[\"SUTTI\"],\"articleSection\":[\"Achats Responsables\",\"Impact\",\"Paysans du Sud\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/ksapa.org\\\/fr\\\/sutti-ameliore-la-vie-des-petits-producteurs-de-caoutchouc\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/sutti-ameliore-la-vie-des-petits-producteurs-de-caoutchouc\\\/\",\"url\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/sutti-ameliore-la-vie-des-petits-producteurs-de-caoutchouc\\\/\",\"name\":\"Impact social : Former les producteurs de caoutchouc en Indon\u00e9sie\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/sutti-ameliore-la-vie-des-petits-producteurs-de-caoutchouc\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/sutti-ameliore-la-vie-des-petits-producteurs-de-caoutchouc\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/1\\\/2023\\\/03\\\/R0000039-scaled.jpg\",\"datePublished\":\"2023-03-14T16:07:50+00:00\",\"dateModified\":\"2025-12-03T14:41:59+00:00\",\"description\":\"D\u00e9couvrez les impacts positifs du programme hybride de Ksapa de formation \u00e0 l'h\u00e9v\u00e9aculture sur les producteurs de caoutchouc indon\u00e9siens\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/sutti-ameliore-la-vie-des-petits-producteurs-de-caoutchouc\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ksapa.org\\\/fr\\\/sutti-ameliore-la-vie-des-petits-producteurs-de-caoutchouc\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/sutti-ameliore-la-vie-des-petits-producteurs-de-caoutchouc\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/1\\\/2023\\\/03\\\/R0000039-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/1\\\/2023\\\/03\\\/R0000039-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"SUTTI am\u00e9liore la vie des petits producteurs de caoutchouc\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/sutti-ameliore-la-vie-des-petits-producteurs-de-caoutchouc\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SUTTI am\u00e9liore la vie des petits producteurs de caoutchouc\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/\",\"name\":\"Ksapa - fr\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/#organization\",\"name\":\"ksapa\",\"url\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/1\\\/2019\\\/06\\\/icone-ksapa.jpg\",\"contentUrl\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/1\\\/2019\\\/06\\\/icone-ksapa.jpg\",\"width\":\"442\",\"height\":\"421\",\"caption\":\"ksapa\"},\"image\":{\"@id\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/KsapaOrg\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/#\\\/schema\\\/person\\\/5c5037e344a16220951fc1019696033f\",\"name\":\"Adrien Covo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/ksapa.org\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Adrien-Covo.jpg\",\"url\":\"https:\\\/\\\/ksapa.org\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Adrien-Covo.jpg\",\"contentUrl\":\"https:\\\/\\\/ksapa.org\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Adrien-Covo.jpg\",\"caption\":\"Adrien Covo\"},\"description\":\"Adrien is a SUTTI Program Officer. He\u2019s responsible for the development, operational implementation, and monitoring of SUTTI programs. He participates in designing financial structuring schemes leveraging SUTTI\u2019s impacts. He has previous experiences in various industries, within public, private, and non-profit organizations. Before joining, he was involved in microfinance and social entrepreneurship initiatives in Cambodia and the Philippines, after working for Danone and RATP. He holds a Master\u2019s in Finance from Paris-Dauphine University, as well as a Master in Management from ESSEC Business School. He speaks French, English, and Spanish.\",\"url\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/author\\\/acovo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Impact social : Former les producteurs de caoutchouc en Indon\u00e9sie","description":"D\u00e9couvrez les impacts positifs du programme hybride de Ksapa de formation \u00e0 l'h\u00e9v\u00e9aculture sur les producteurs de caoutchouc indon\u00e9siens","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ksapa.org\/fr\/sutti-ameliore-la-vie-des-petits-producteurs-de-caoutchouc\/","og_locale":"fr_FR","og_type":"article","og_title":"Impact social : Former les producteurs de caoutchouc en Indon\u00e9sie","og_description":"D\u00e9couvrez les impacts positifs du programme hybride de Ksapa de formation \u00e0 l'h\u00e9v\u00e9aculture sur les producteurs de caoutchouc indon\u00e9siens","og_url":"https:\/\/ksapa.org\/fr\/sutti-ameliore-la-vie-des-petits-producteurs-de-caoutchouc\/","og_site_name":"Ksapa - fr","article_published_time":"2023-03-14T16:07:50+00:00","article_modified_time":"2025-12-03T14:41:59+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/ksapa.org\/fr\/wp-content\/uploads\/sites\/1\/2023\/03\/R0000039-scaled.jpg","type":"image\/jpeg"}],"author":"Adrien Covo","twitter_card":"summary_large_image","twitter_creator":"@KsapaOrg","twitter_site":"@KsapaOrg","twitter_misc":{"\u00c9crit par":"Adrien Covo","Dur\u00e9e de lecture estim\u00e9e":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ksapa.org\/fr\/sutti-ameliore-la-vie-des-petits-producteurs-de-caoutchouc\/#article","isPartOf":{"@id":"https:\/\/ksapa.org\/fr\/sutti-ameliore-la-vie-des-petits-producteurs-de-caoutchouc\/"},"author":{"name":"Adrien Covo","@id":"https:\/\/ksapa.org\/fr\/#\/schema\/person\/5c5037e344a16220951fc1019696033f"},"headline":"SUTTI am\u00e9liore la vie des petits producteurs de caoutchouc","datePublished":"2023-03-14T16:07:50+00:00","dateModified":"2025-12-03T14:41:59+00:00","mainEntityOfPage":{"@id":"https:\/\/ksapa.org\/fr\/sutti-ameliore-la-vie-des-petits-producteurs-de-caoutchouc\/"},"wordCount":1520,"commentCount":0,"publisher":{"@id":"https:\/\/ksapa.org\/fr\/#organization"},"image":{"@id":"https:\/\/ksapa.org\/fr\/sutti-ameliore-la-vie-des-petits-producteurs-de-caoutchouc\/#primaryimage"},"thumbnailUrl":"https:\/\/ksapa.org\/fr\/wp-content\/uploads\/sites\/1\/2023\/03\/R0000039-scaled.jpg","keywords":["SUTTI"],"articleSection":["Achats Responsables","Impact","Paysans du Sud"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ksapa.org\/fr\/sutti-ameliore-la-vie-des-petits-producteurs-de-caoutchouc\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ksapa.org\/fr\/sutti-ameliore-la-vie-des-petits-producteurs-de-caoutchouc\/","url":"https:\/\/ksapa.org\/fr\/sutti-ameliore-la-vie-des-petits-producteurs-de-caoutchouc\/","name":"Impact social : Former les producteurs de caoutchouc en Indon\u00e9sie","isPartOf":{"@id":"https:\/\/ksapa.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ksapa.org\/fr\/sutti-ameliore-la-vie-des-petits-producteurs-de-caoutchouc\/#primaryimage"},"image":{"@id":"https:\/\/ksapa.org\/fr\/sutti-ameliore-la-vie-des-petits-producteurs-de-caoutchouc\/#primaryimage"},"thumbnailUrl":"https:\/\/ksapa.org\/fr\/wp-content\/uploads\/sites\/1\/2023\/03\/R0000039-scaled.jpg","datePublished":"2023-03-14T16:07:50+00:00","dateModified":"2025-12-03T14:41:59+00:00","description":"D\u00e9couvrez les impacts positifs du programme hybride de Ksapa de formation \u00e0 l'h\u00e9v\u00e9aculture sur les producteurs de caoutchouc indon\u00e9siens","breadcrumb":{"@id":"https:\/\/ksapa.org\/fr\/sutti-ameliore-la-vie-des-petits-producteurs-de-caoutchouc\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ksapa.org\/fr\/sutti-ameliore-la-vie-des-petits-producteurs-de-caoutchouc\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/ksapa.org\/fr\/sutti-ameliore-la-vie-des-petits-producteurs-de-caoutchouc\/#primaryimage","url":"https:\/\/ksapa.org\/fr\/wp-content\/uploads\/sites\/1\/2023\/03\/R0000039-scaled.jpg","contentUrl":"https:\/\/ksapa.org\/fr\/wp-content\/uploads\/sites\/1\/2023\/03\/R0000039-scaled.jpg","width":2560,"height":1707,"caption":"SUTTI am\u00e9liore la vie des petits producteurs de caoutchouc"},{"@type":"BreadcrumbList","@id":"https:\/\/ksapa.org\/fr\/sutti-ameliore-la-vie-des-petits-producteurs-de-caoutchouc\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ksapa.org\/fr\/"},{"@type":"ListItem","position":2,"name":"SUTTI am\u00e9liore la vie des petits producteurs de caoutchouc"}]},{"@type":"WebSite","@id":"https:\/\/ksapa.org\/fr\/#website","url":"https:\/\/ksapa.org\/fr\/","name":"Ksapa - fr","description":"","publisher":{"@id":"https:\/\/ksapa.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ksapa.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/ksapa.org\/fr\/#organization","name":"ksapa","url":"https:\/\/ksapa.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/ksapa.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/ksapa.org\/fr\/wp-content\/uploads\/sites\/1\/2019\/06\/icone-ksapa.jpg","contentUrl":"https:\/\/ksapa.org\/fr\/wp-content\/uploads\/sites\/1\/2019\/06\/icone-ksapa.jpg","width":"442","height":"421","caption":"ksapa"},"image":{"@id":"https:\/\/ksapa.org\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/KsapaOrg"]},{"@type":"Person","@id":"https:\/\/ksapa.org\/fr\/#\/schema\/person\/5c5037e344a16220951fc1019696033f","name":"Adrien Covo","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/ksapa.org\/wp-content\/uploads\/2023\/07\/Adrien-Covo.jpg","url":"https:\/\/ksapa.org\/wp-content\/uploads\/2023\/07\/Adrien-Covo.jpg","contentUrl":"https:\/\/ksapa.org\/wp-content\/uploads\/2023\/07\/Adrien-Covo.jpg","caption":"Adrien Covo"},"description":"Adrien is a SUTTI Program Officer. He\u2019s responsible for the development, operational implementation, and monitoring of SUTTI programs. He participates in designing financial structuring schemes leveraging SUTTI\u2019s impacts. He has previous experiences in various industries, within public, private, and non-profit organizations. Before joining, he was involved in microfinance and social entrepreneurship initiatives in Cambodia and the Philippines, after working for Danone and RATP. He holds a Master\u2019s in Finance from Paris-Dauphine University, as well as a Master in Management from ESSEC Business School. He speaks French, English, and Spanish.","url":"https:\/\/ksapa.org\/fr\/author\/acovo\/"}]}},"_links":{"self":[{"href":"https:\/\/ksapa.org\/fr\/wp-json\/wp\/v2\/posts\/7364","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ksapa.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ksapa.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ksapa.org\/fr\/wp-json\/wp\/v2\/users\/75"}],"replies":[{"embeddable":true,"href":"https:\/\/ksapa.org\/fr\/wp-json\/wp\/v2\/comments?post=7364"}],"version-history":[{"count":5,"href":"https:\/\/ksapa.org\/fr\/wp-json\/wp\/v2\/posts\/7364\/revisions"}],"predecessor-version":[{"id":10745,"href":"https:\/\/ksapa.org\/fr\/wp-json\/wp\/v2\/posts\/7364\/revisions\/10745"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ksapa.org\/fr\/wp-json\/wp\/v2\/media\/7372"}],"wp:attachment":[{"href":"https:\/\/ksapa.org\/fr\/wp-json\/wp\/v2\/media?parent=7364"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ksapa.org\/fr\/wp-json\/wp\/v2\/categories?post=7364"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ksapa.org\/fr\/wp-json\/wp\/v2\/tags?post=7364"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}