{"id":2680,"count":1,"description":"","link":"https:\/\/ksapa.org\/fr\/tag\/innovation-technologique\/","name":"innovation technologique","slug":"innovation-technologique","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>innovation technologique - Ksapa - fr<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ksapa.org\/fr\/tag\/innovation-technologique\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"innovation technologique - Ksapa - fr\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ksapa.org\/fr\/tag\/innovation-technologique\/\" \/>\n<meta property=\"og:site_name\" content=\"Ksapa - fr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@KsapaOrg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/tag\\\/innovation-technologique\\\/\",\"url\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/tag\\\/innovation-technologique\\\/\",\"name\":\"innovation technologique - Ksapa - fr\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/tag\\\/innovation-technologique\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/tag\\\/innovation-technologique\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"innovation technologique\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/\",\"name\":\"Ksapa - fr\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/#organization\",\"name\":\"ksapa\",\"url\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/1\\\/2019\\\/06\\\/icone-ksapa.jpg\",\"contentUrl\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/1\\\/2019\\\/06\\\/icone-ksapa.jpg\",\"width\":\"442\",\"height\":\"421\",\"caption\":\"ksapa\"},\"image\":{\"@id\":\"https:\\\/\\\/ksapa.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/KsapaOrg\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"innovation technologique - Ksapa - fr","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ksapa.org\/fr\/tag\/innovation-technologique\/","og_locale":"fr_FR","og_type":"article","og_title":"innovation technologique - Ksapa - fr","og_url":"https:\/\/ksapa.org\/fr\/tag\/innovation-technologique\/","og_site_name":"Ksapa - fr","twitter_card":"summary_large_image","twitter_site":"@KsapaOrg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/ksapa.org\/fr\/tag\/innovation-technologique\/","url":"https:\/\/ksapa.org\/fr\/tag\/innovation-technologique\/","name":"innovation technologique - Ksapa - fr","isPartOf":{"@id":"https:\/\/ksapa.org\/fr\/#website"},"breadcrumb":{"@id":"https:\/\/ksapa.org\/fr\/tag\/innovation-technologique\/#breadcrumb"},"inLanguage":"fr-FR"},{"@type":"BreadcrumbList","@id":"https:\/\/ksapa.org\/fr\/tag\/innovation-technologique\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ksapa.org\/fr\/"},{"@type":"ListItem","position":2,"name":"innovation technologique"}]},{"@type":"WebSite","@id":"https:\/\/ksapa.org\/fr\/#website","url":"https:\/\/ksapa.org\/fr\/","name":"Ksapa - fr","description":"","publisher":{"@id":"https:\/\/ksapa.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ksapa.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/ksapa.org\/fr\/#organization","name":"ksapa","url":"https:\/\/ksapa.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/ksapa.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/ksapa.org\/fr\/wp-content\/uploads\/sites\/1\/2019\/06\/icone-ksapa.jpg","contentUrl":"https:\/\/ksapa.org\/fr\/wp-content\/uploads\/sites\/1\/2019\/06\/icone-ksapa.jpg","width":"442","height":"421","caption":"ksapa"},"image":{"@id":"https:\/\/ksapa.org\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/KsapaOrg"]}]}},"_links":{"self":[{"href":"https:\/\/ksapa.org\/fr\/wp-json\/wp\/v2\/tags\/2680","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ksapa.org\/fr\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/ksapa.org\/fr\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/ksapa.org\/fr\/wp-json\/wp\/v2\/posts?tags=2680"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}